{"id":16340,"date":"2017-11-02T16:35:09","date_gmt":"2017-11-02T20:35:09","guid":{"rendered":"https:\/\/firstglobal.pnj9zv60-liquidwebsites.com\/?page_id=16340"},"modified":"2026-04-24T16:28:46","modified_gmt":"2026-04-24T20:28:46","slug":"gsc","status":"publish","type":"page","link":"https:\/\/first.global\/fr\/gsc\/","title":{"rendered":"Global STEM Corps"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><div data-q_header_style=\"dark\" class=\"vc_row wpb_row section vc_row-fluid  full_screen_section\" style='background-image:url(https:\/\/i0.wp.com\/first.global\/wp-content\/uploads\/2021\/02\/Cameroon-robot-kit-dark--e1613580311298.jpg?fit=1601%2C892&ssl=1); text-align:center;'><div class=\"full_section_inner clearfix\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"separator  transparent\" style=\"height: 200px;\"><\/div>\n\t<div class=\"wpb_text_column wpb_content_element\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h1 style=\"text-align: center;\" class=\"translation-block\"><span style=\"color: #ffffff\">Le Global STEM Corps de <i>FIRST<\/i> Global<\/span><\/h1>\n\n\t\t<\/div>\n\t<\/div><div class=\"separator  transparent\" style=\"height: 200px;\"><\/div><\/div><\/div><\/div><\/div><\/div><div      class=\"vc_row wpb_row section vc_row-fluid  grid_section\" style=' text-align:left;'><div class=\"section_inner clearfix\"><div class='section_inner_margin clearfix'><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"vc_empty_space\"  style=\"height: 30px\" >\n\t<span class=\"vc_empty_space_inner\">\n\t\t<span class=\"empty_space_image\"  ><\/span>\n\t<\/span>\n<\/div>\n\t<div class=\"wpb_text_column wpb_content_element\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h2>UN KIT, POSSIBILIT\u00c9S INFINIES.<\/h2>\n\n\t\t<\/div>\n\t<\/div><div class=\"separator  transparent\" style=\"height: 15px;\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div      class=\"vc_row wpb_row section vc_row-fluid  grid_section\" style=' text-align:left;'><div class=\"section_inner clearfix\"><div class='section_inner_margin clearfix'><div class=\"wpb_column vc_column_container vc_col-sm-6\"><div class=\"vc_column-inner vc_custom_1611941779532\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p class=\"translation-block\">Le <em>FIRST<\/em> Global \"Global STEM Corps\" (GSC) est la r\u00e9ponse de <em>FIRST<\/em> Global au 21\u00e8me si\u00e8cle \u00e0 un monde qui a besoin d'une g\u00e9n\u00e9ration inspir\u00e9e de jeunes adultes pr\u00eats \u00e0 relever les d\u00e9fis mondiaux. Les volontaires qualifi\u00e9s du GSC font partie d'une \u00e9quipe de conseillers qui encadre une \u00e9quipe nationale de <em>FIRST<\/em> Global pendant qu'elle construit son robot. En travaillant avec des \u00e9tudiants du monde entier tout au long de ce processus, les volontaires du GSC aident les concurrents de <em>FIRST<\/em> Global \u00e0 atteindre tout ce dont ils sont capables et les incitent \u00e0 mener une vie \u00e9panouissante, passionnante et gratifiante gr\u00e2ce aux STIM. Le GSC apporte les \u00e9l\u00e9ments universels de la science, de la coop\u00e9ration et de la comp\u00e9tition sur la sc\u00e8ne mondiale.<\/p>\n\n\t\t<\/div>\n\t<\/div><div class=\"separator  transparent\" style=\"height: 15px;\"><\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-6\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class='q_elements_holder two_columns responsive_mode_from_768' ><div class='q_elements_item' data-animation='no' data-item-class='q_elements_holder_custom_992860' style='background-color:#f4f4f4;'><div class='q_elements_item_inner'><div class='q_elements_item_content q_elements_holder_custom_992860' style='padding:40px 10px 20px 10px'><div class='q_icon_with_title medium normal_icon center'><div class=\"icon_holder\" style=\" \"><span data-icon-type=\"normal\" class=\"qode_iwt_icon_holder q_font_awsome_icon fa-3x\"><i class=\"qode_icon_font_awesome fa fa-users qode_iwt_icon_element\"><\/i><\/span><\/div><div class=\"icon_text_holder\" style=\"\"><div class=\"icon_text_inner\" style=\"\"><h3 class=\"icon_title\" style=\"color: #3498db;\">1.000+ \u00c9TUDIANTS<\/h3><p style=''>encadr\u00e9s par le GSC depuis 2017.<\/p><\/div><\/div><\/div><\/div><\/div><\/div><div class='q_elements_item' data-animation='no' data-item-class='q_elements_holder_custom_980893' style='background-color:#f9f9f9;'><div class='q_elements_item_inner'><div class='q_elements_item_content q_elements_holder_custom_980893' style='padding:40px 10px 20px 10px'><div class='q_icon_with_title medium normal_icon center'><div class=\"icon_holder\" style=\" \"><span data-icon-type=\"normal\" class=\"qode_iwt_icon_holder q_font_awsome_icon fa-3x\"><i class=\"qode_icon_font_awesome_5 fa5 fa fa-wrench qode_iwt_icon_element\"><\/i><\/span><\/div><div class=\"icon_text_holder\" style=\"\"><div class=\"icon_text_inner\" style=\"\"><h3 class=\"icon_title\" style=\"color: #3498db;\">150+ ROBOTS<\/h3><p style=''>construits gr\u00e2ce au soutien du SGC depuis 2017.<\/p><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_empty_space\"  style=\"height: 30px\" >\n\t<span class=\"vc_empty_space_inner\">\n\t\t<span class=\"empty_space_image\"  ><\/span>\n\t<\/span>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><div      class=\"vc_row wpb_row section vc_row-fluid  grid_section\" style=' text-align:left;'><div class=\"section_inner clearfix\"><div class='section_inner_margin clearfix'><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h2>NOTRE MISSION<\/h2>\n\n\t\t<\/div>\n\t<\/div><div class=\"separator  transparent\" style=\"height: 10px;\"><\/div>\n\t<div class=\"wpb_text_column wpb_content_element\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p class=\"translation-block\">La mission du GSC est d'\u00e9quiper, de former, d'encadrer et d'inspirer des centaines d'\u00e9tudiants participant au <em>FIRST<\/em> Global Challenge chaque ann\u00e9e. Les volontaires de les \u00e9quipes de conseillers sont jumel\u00e9es \u00e0 des \u00e9tudiants de diff\u00e9rentes r\u00e9gions du monde, o\u00f9 les jeunes adultes ont rarement acc\u00e8s aux niveaux de financement n\u00e9cessaires pour poursuivre une \u00e9ducation s\u00e9rieuse aux STIM. Les \u00e9quipes de conseillers de la GSC utiliseront leurs connaissances et leur enthousiasme pour STIM non seulement pour augmenter les opportunit\u00e9s de <i>FIRST<\/i> Global participants, mais pour les inciter \u00e0 devenir plus de gens comme Albert Einstein, Mae Jemison et Stephen Hawking.<\/p>\n\n\t\t<\/div>\n\t<\/div><div class=\"separator  transparent\" style=\"height: 5px;\"><\/div>\n\t<div class=\"wpb_text_column wpb_content_element\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>Au cours des derni\u00e8res d\u00e9cennies, les pays \u00e0 revenu \u00e9lev\u00e9 ont consid\u00e9rablement progress\u00e9 et investi dans l\u2019enseignement des STIM, ce qui a conduit \u00e0 de nombreuses d\u00e9couvertes parmi les plus importantes de l\u2019\u00e8re moderne - processeurs \u00e0 grande vitesse et moteurs hybrides, proth\u00e8ses avanc\u00e9es et drones miniaturis\u00e9s. Malheureusement, comme des investissements similaires ne sont pas r\u00e9alis\u00e9s dans des pays moins fortun\u00e9s sur le plan \u00e9conomique, des centaines de millions d'\u00e9tudiants dans les pays m\u00eames o\u00f9 l'\u00e9ducation aux STIM est le plus n\u00e9cessaire sont laiss\u00e9s pour compte - et continueront de l'\u00eatre \u00e0 moins que ceux qui poss\u00e8dent les connaissances et la volont\u00e9 n\u00e9cessaires la diff\u00e9rence intervient pour aider.<\/p>\n\n\t\t<\/div>\n\t<\/div><div class=\"vc_empty_space\"  style=\"height: 30px\" >\n\t<span class=\"vc_empty_space_inner\">\n\t\t<span class=\"empty_space_image\"  ><\/span>\n\t<\/span>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><div      class=\"vc_row wpb_row section vc_row-fluid  vc_custom_1611851923770\" style=' text-align:left;'><div class=\"full_section_inner clearfix\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"separator  transparent\" style=\"height: 15px;\"><\/div><div      class=\"vc_row wpb_row section vc_row-fluid vc_inner  grid_section\" style=' text-align:left;'><div class=\"section_inner clearfix\"><div class='section_inner_margin clearfix'><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_video_widget wpb_content_element vc_clearfix   vc_video-aspect-ratio-169 vc_video-el-width-100 vc_video-align-center\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n\t\t\t<div class=\"wpb_video_wrapper\"><span class=\"embed-youtube\" style=\"text-align:center; display: block;\"><iframe loading=\"lazy\" class=\"youtube-player\" width=\"1060\" height=\"597\" src=\"https:\/\/www.youtube.com\/embed\/AvnBIKED2RE?version=3&#038;rel=1&#038;showsearch=0&#038;showinfo=1&#038;iv_load_policy=1&#038;fs=1&#038;hl=fr-FR&#038;autohide=2&#038;wmode=transparent\" allowfullscreen=\"true\" style=\"border:0;\" sandbox=\"allow-scripts allow-same-origin allow-popups allow-presentation allow-popups-to-escape-sandbox\"><\/iframe><\/span><\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div><div class=\"separator  transparent\" style=\"height: 15px;\"><\/div><\/div><\/div><\/div><\/div><\/div><div      class=\"vc_row wpb_row section vc_row-fluid  grid_section\" style=' text-align:left;'><div class=\"section_inner clearfix\"><div class='section_inner_margin clearfix'><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"vc_empty_space\"  style=\"height: 30px\" >\n\t<span class=\"vc_empty_space_inner\">\n\t\t<span class=\"empty_space_image\"  ><\/span>\n\t<\/span>\n<\/div>\n\t<div class=\"wpb_text_column wpb_content_element\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h2>QUE FONT LES VOLONTAIRES DU GSC?<\/h2>\n\n\t\t<\/div>\n\t<\/div><div class=\"separator  transparent\" style=\"height: 10px;\"><\/div>\n\t<div class=\"wpb_text_column wpb_content_element\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>Les volontaires sont charg\u00e9s d'assurer un mentorat virtuel <em>FIRST<\/em> \u00c9quipes mondiales. Cela se fait par le biais d'une \u00e9quipe de conseillers, o\u00f9 un groupe de volontaires adopte un pays et travaille avec lui sur une base hebdomadaire pour l'aider \u00e0 se pr\u00e9parer \u00e0 l'\u00e9v\u00e9nement. <em>FIRST<\/em> D\u00e9fi mondial. La plupart des \u00e9quipes travaillent ensemble au moins une fois par semaine via Zoom, Microsoft Teams, Google Meet, WhatsApp ou d'autres services de messagerie instantan\u00e9e. Les \u00e9quipes de conseillers ne sont pas tenues de se rendre dans le pays ou d'acheter un passeport officiel. <em>FIRST<\/em> Global, mais les \u00e9quipes int\u00e9ress\u00e9es peuvent le faire par l'interm\u00e9diaire de REV Robotics. Votre r\u00f4le en tant qu'\u00e9quipe de conseillers est de guider l'\u00e9quipe qui vous est assign\u00e9e dans le processus de construction du robot, mais pas de construire le robot pour elle ! Les \u00e9quipes ont souvent besoin d'aide dans d'autres domaines tels que l'exp\u00e9rience des nouvelles technologies, le mat\u00e9riel de marketing et de sensibilisation, la mani\u00e8re de raconter leur histoire, les r\u00e9compenses, le cahier d'ing\u00e9nierie, etc.<\/p>\n\n\t\t<\/div>\n\t<\/div><div class=\"separator  transparent\" style=\"height: 5px;\"><\/div><div      class=\"vc_row wpb_row section vc_row-fluid vc_inner\" style=' text-align:left;'><div class=\"full_section_inner clearfix\"><div class=\"wpb_column vc_column_container vc_col-sm-8\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p class=\"translation-block\">Les \u00c9quipes de Conseillers vont des \u00e9quipes enti\u00e8res de <em>FIRST<\/em> Tech Challenge (FTC) et <em>FIRST<\/em> Robotics Competition (FRC), aux \u00e9tudiants universitaires et aux d\u00e9partements d'ing\u00e9nierie, en passant par des groupes d'ing\u00e9nieurs professionnels. Ces volontaires \u00e9quilibrent leurs horaires charg\u00e9s, les d\u00e9calages horaires et les d\u00e9fis technologiques pour inspirer les \u00e9quipes de <em>FIRST<\/em> Global en leur fournissant une aide m\u00e9canique, \u00e9lectrique et de programmation, ainsi que des conseils strat\u00e9giques.<\/p>\n<p>&nbsp;<\/p>\n<p class=\"translation-block\">Bien que les demandes de travailler avec une \u00e9quipe sp\u00e9cifique soient prises en consid\u00e9ration, le besoin global d'une \u00e9quipe est plac\u00e9 au-dessus de cela. Certaines \u00e9quipes participantes de <em>FIRST<\/em> Global n'ont pas besoin d'aide, en particulier si elles sont une \u00e9quipe de robotique existante ou si elles ont une autre exp\u00e9rience dans la construction de robots. Les \u00e9quipes qui participent au GSC ont souvent peu ou pas d'exp\u00e9rience. Les comp\u00e9tences linguistiques sont \u00e9galement un \u00e9l\u00e9ment principal de l'attribution d'une \u00e9quipe de conseillers. Nous encourageons particuli\u00e8rement les \u00e9quipes qui parlent couramment l'espagnol, le fran\u00e7ais, l'arabe et le portugais \u00e0 postuler !<\/p>\n\n\t\t<\/div>\n\t<\/div><div class=\"separator  transparent\" style=\"height: 5px;\"><\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_single_image wpb_content_element vc_align_right\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/i0.wp.com\/first.global\/wp-content\/uploads\/2021\/02\/GSC-for-Team-Burundi-small.jpg?fit=1024%2C768&amp;ssl=1\" class=\"vc_single_image-img attachment-large\" alt=\"\" title=\"Le SGC pour l&#039;\u00e9quipe Burundi petite\" srcset=\"https:\/\/i0.wp.com\/first.global\/wp-content\/uploads\/2021\/02\/GSC-for-Team-Burundi-small.jpg?w=1200&amp;ssl=1 1200w, https:\/\/i0.wp.com\/first.global\/wp-content\/uploads\/2021\/02\/GSC-for-Team-Burundi-small.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/first.global\/wp-content\/uploads\/2021\/02\/GSC-for-Team-Burundi-small.jpg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/first.global\/wp-content\/uploads\/2021\/02\/GSC-for-Team-Burundi-small.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/first.global\/wp-content\/uploads\/2021\/02\/GSC-for-Team-Burundi-small.jpg?resize=16%2C12&amp;ssl=1 16w, https:\/\/i0.wp.com\/first.global\/wp-content\/uploads\/2021\/02\/GSC-for-Team-Burundi-small.jpg?resize=800%2C600&amp;ssl=1 800w, https:\/\/i0.wp.com\/first.global\/wp-content\/uploads\/2021\/02\/GSC-for-Team-Burundi-small.jpg?resize=700%2C525&amp;ssl=1 700w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" data-attachment-id=\"28646\" data-permalink=\"https:\/\/first.global\/fr\/?attachment_id=28646\" data-orig-file=\"https:\/\/i0.wp.com\/first.global\/wp-content\/uploads\/2021\/02\/GSC-for-Team-Burundi-small.jpg?fit=1200%2C900&amp;ssl=1\" data-orig-size=\"1200,900\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.8&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPhone 7 Plus&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1527934741&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.99&quot;,&quot;iso&quot;:&quot;40&quot;,&quot;shutter_speed&quot;:&quot;0.066666666666667&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"GSC for Team Burundi small\" data-image-description=\"&lt;p&gt;GSC Volunteers&lt;\/p&gt;\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/first.global\/wp-content\/uploads\/2021\/02\/GSC-for-Team-Burundi-small.jpg?fit=1024%2C768&amp;ssl=1\" \/><\/div>\n\t\t<\/div>\n\t<\/div>\n<div class=\"separator  transparent\" style=\"height: 5px;\"><\/div><\/div><\/div><\/div><\/div><\/div>\n\t<div class=\"wpb_text_column wpb_content_element\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p class=\"translation-block\">Si votre \u00e9quipe souhaite faire partie du programme officiel, toutes les demandes de collaboration avec une \u00e9quipe doivent passer par <em>FIRST<\/em> Global. Veuillez ne pas contacter une \u00e9quipe de votre propre chef, car vous (et l'\u00e9quipe) ne serez pas consid\u00e9r\u00e9s comme faisant partie du Global STEM Corps officiel.<\/p>\n\n\t\t<\/div>\n\t<\/div><div class=\"vc_empty_space\"  style=\"height: 30px\" >\n\t<span class=\"vc_empty_space_inner\">\n\t\t<span class=\"empty_space_image\"  ><\/span>\n\t<\/span>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><div     data-q_header_style=\"dark\" class=\"vc_row wpb_row section vc_row-fluid  full_screen_section\" style='background-image:url(https:\/\/i0.wp.com\/first.global\/wp-content\/uploads\/2021\/02\/Team-Honduras-dark.jpg?fit=1500%2C678&ssl=1); text-align:center;'><div class=\"full_section_inner clearfix\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"separator  transparent\" style=\"height: 100px;\"><\/div><div      class=\"vc_row wpb_row section vc_row-fluid vc_inner  grid_section\" style=' text-align:center;'><div class=\"section_inner clearfix\"><div class='section_inner_margin clearfix'><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h2 style=\"text-align: center;\" class=\"translation-block\"><strong><span style=\"color: #ffffff\">\u201cJe dois dire que c'est l'une des exp\u00e9riences les plus enrichissantes de toute ma vie. Ces enfants sont parmi les \u00eatres humains les plus brillants, les plus reconnaissants et les plus gracieux que j'ai jamais eu le plaisir de conna\u00eetre. L'exp\u00e9rience de <em>FIRST<\/em> Global a donn\u00e9 \u00e0 ces enfants un sentiment de valeur personnelle qu'il serait difficile de produire autrement. Vous changez des vies!\"<\/span><\/strong><\/h2>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center; font-size: 20px;\"><span style=\"color: #ffffff;\">-Alan, mentor de l'\u00c9quipe Conseillers du GSC aupr\u00e8s de \u00c9quipe Honduras<\/span><\/p>\n\n\t\t<\/div>\n\t<\/div><div class=\"separator  transparent\" style=\"height: 5px;\"><\/div><a  itemprop=\"url\" href=\"\/fr\/stories\/Alan\/\" target=\"_self\" data-hover-background-color=\"#ffffff\" data-hover-border-color=\"#ffffff\" data-hover-color=\"#000000\" class=\"qbutton  default\" style=\"color: #ffffff; border-color: #ffffff; background-color:rgba(0,0,0,0.01);\">EN SAVOIR PLUS SUR L'HISTOIRE D'ALAN<\/a><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"separator  transparent\" style=\"height: 100px;\"><\/div><\/div><\/div><\/div><\/div><\/div><div      class=\"vc_row wpb_row section vc_row-fluid  grid_section\" style=' text-align:left;'><div class=\"section_inner clearfix\"><div class='section_inner_margin clearfix'><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"vc_empty_space\"  style=\"height: 30px\" >\n\t<span class=\"vc_empty_space_inner\">\n\t\t<span class=\"empty_space_image\"  ><\/span>\n\t<\/span>\n<\/div>\n\t<div class=\"wpb_text_column wpb_content_element\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h2>PR\u00caT \u00c0 VOUS REJOINDRE?<\/h2>\n\n\t\t<\/div>\n\t<\/div><div class=\"separator  transparent\" style=\"height: 10px;\"><\/div><div      class=\"vc_row wpb_row section vc_row-fluid vc_inner\" style=' text-align:left;'><div class=\"full_section_inner clearfix\"><div class=\"wpb_column vc_column_container vc_col-sm-8\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>Le Global STEM Corps a besoin de personnes comme VOUS pour vous aider \u00e0 former la g\u00e9n\u00e9ration la plus performante et la plus performante sur le plan technologique \u00e0 ce jour. La science, la technologie, l'ing\u00e9nierie et les math\u00e9matiques peuvent cr\u00e9er un monde meilleur pour tous.<\/p>\n<p>&nbsp;<\/p>\n<p>Les \u00e9quipes de conseillers du SGC sont invit\u00e9es \u00e0 se mettre \u00e0 la disposition de l'\u00e9quipe ou des \u00e9quipes qu'elles adoptent pendant plusieurs heures au moins une fois par semaine, le temps consacr\u00e9 \u00e0 l'encadrement des \u00e9tudiants \u00e9tant r\u00e9parti sur la semaine ou sur un jour sp\u00e9cifique chaque semaine. En g\u00e9n\u00e9ral, les \u00e9quipes organisent un appel vid\u00e9o et \u00e9changent ensuite des messages tout au long de la semaine. Un rapport hebdomadaire sur les progr\u00e8s de l'\u00e9quipe est \u00e9galement requis.<\/p>\n<p>&nbsp;<\/p>\n<p>Le Global STEM Corps est ouvert \u00e0 l'inscription ! Vous pouvez inscrire votre \u00e9quipe <a href=\"https:\/\/form.jotform.com\/260897887516074\">ici<\/a>. La plupart des \u00e9quipes qui sont des \u00e9quipes FTC ou FRC recevront une \u00e9quipe \u00e0 encadrer.  La date de d\u00e9but du programme varie d'une \u00e9quipe \u00e0 l'autre, mais la plupart des \u00e9quipes de conseillers sont reli\u00e9es \u00e0 une \u00e9quipe participante. <em>FIRST <\/em>Global team tout au long des mois de juin et juillet, au fur et \u00e0 mesure que les \u00e9quipes s'inscrivent et que les \u00e9tudiants sont pr\u00eats \u00e0 commencer \u00e0 travailler. Les personnes inscrites recevront des mises \u00e0 jour d\u00e8s qu'elles seront disponibles.<\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #3498db;\"><span style=\"caret-color: #3498db;\"><b>CONDITIONS<\/b><\/span><\/span><strong style=\"color: #3498db;\">:<\/strong><\/p>\n<ul>\n<li>Doit parler couramment l'anglais.<\/li>\n<li>Doit avoir acc\u00e8s \u00e0 un ordinateur et \u00e0 un service Internet fiable.<\/li>\n<li>Doit \u00eatre disponible au moins six heures par semaine (le plus le mieux).<\/li>\n<li>Doit s\u2019engager \u00e0 \u00eatre un mentor jusqu\u2019\u00e0 la fin de la p\u00e9riode de construction.<\/li>\n<li>Doit avoir une exp\u00e9rience ou une passion pour la robotique, l'ing\u00e9nierie, la programmation ou l'\u00e9lectronique.<\/li>\n<li>Une passion pour la diffusion des connaissances et la connexion avec des personnes du monde entier.<\/li>\n<li>Les comp\u00e9tences en langues \u00e9trang\u00e8res sont un atout mais non requis.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #3498db;\"><span style=\"caret-color: #3498db;\"><b>EXP\u00c9RIENCE\/QUALIFICATIONS PR\u00c9F\u00c9R\u00c9ES DANS AU MOINS UN DES DOMAINES SUIVANTS<\/b><\/span><\/span><strong style=\"color: #3498db;\">:<\/strong><\/p>\n<ul>\n<li>Exp\u00e9rience de base en g\u00e9nie m\u00e9canique (en particulier avec les syst\u00e8mes d'assemblage de kits robotiques).<\/li>\n<li>Ma\u00eetrise de la programmation avec Java (en particulier au sein d'Android Studios) ou d'autres syst\u00e8mes de programmation \u00e0 base d'images (tels que Google Blockly).<\/li>\n<li>Familiarit\u00e9 avec les cartes Arduino et l'environnement de d\u00e9veloppement int\u00e9gr\u00e9 (IDE) Arduino pour la programmation.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>Toutes les questions concernant l\u2019adh\u00e9sion au GSC peuvent \u00eatre envoy\u00e9es \u00e0 gsc@first.global.<\/p>\n\n\t\t<\/div>\n\t<\/div><div class=\"separator  transparent\" style=\"margin-top: 10px;\"><\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_single_image wpb_content_element vc_align_left\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" width=\"601\" height=\"800\" src=\"https:\/\/i0.wp.com\/first.global\/wp-content\/uploads\/2021\/02\/Ken-from-Yale-chatting-with-Team-Cambodia-GSC.jpg?fit=601%2C800&amp;ssl=1\" class=\"vc_single_image-img attachment-large\" alt=\"\" title=\"Ken de Yale discute avec l&#039;\u00e9quipe Cambodge GSC\" srcset=\"https:\/\/i0.wp.com\/first.global\/wp-content\/uploads\/2021\/02\/Ken-from-Yale-chatting-with-Team-Cambodia-GSC.jpg?w=601&amp;ssl=1 601w, https:\/\/i0.wp.com\/first.global\/wp-content\/uploads\/2021\/02\/Ken-from-Yale-chatting-with-Team-Cambodia-GSC.jpg?resize=225%2C300&amp;ssl=1 225w, https:\/\/i0.wp.com\/first.global\/wp-content\/uploads\/2021\/02\/Ken-from-Yale-chatting-with-Team-Cambodia-GSC.jpg?resize=9%2C12&amp;ssl=1 9w\" sizes=\"auto, (max-width: 601px) 100vw, 601px\" data-attachment-id=\"28641\" data-permalink=\"https:\/\/first.global\/fr\/?attachment_id=28641\" data-orig-file=\"https:\/\/i0.wp.com\/first.global\/wp-content\/uploads\/2021\/02\/Ken-from-Yale-chatting-with-Team-Cambodia-GSC.jpg?fit=601%2C800&amp;ssl=1\" data-orig-size=\"601,800\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Ken from Yale chatting with Team Cambodia GSC\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/first.global\/wp-content\/uploads\/2021\/02\/Ken-from-Yale-chatting-with-Team-Cambodia-GSC.jpg?fit=601%2C800&amp;ssl=1\" \/><\/div>\n\t\t<\/div>\n\t<\/div>\n<div class=\"separator  transparent\" style=\"margin-top: 10px;\"><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_empty_space\"  style=\"height: 50px\" >\n\t<span class=\"vc_empty_space_inner\">\n\t\t<span class=\"empty_space_image\"  ><\/span>\n\t<\/span>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"LE PREMIER GLOBAL 'Global STEM Corps' UN KIT, DES POSSIBILIT\u00c9S ENDOUBL\u00c9ES. Le \"Global STEM Corps\" (GSC) de FIRST Global est la r\u00e9ponse de FIRST Global au 21e si\u00e8cle \u00e0 un monde qui a besoin d'une g\u00e9n\u00e9ration inspir\u00e9e de jeunes adultes pr\u00eats \u00e0 relever les d\u00e9fis mondiaux. Les volontaires qualifi\u00e9s du GSC...","protected":false},"author":1,"featured_media":28637,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"full_width.php","meta":{"give_campaign_id":0,"_crdt_document":"","footnotes":""},"class_list":["post-16340","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Global STEM Corps - FIRST Global<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/first.global\/fr\/gsc\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Global STEM Corps - FIRST Global\" \/>\n<meta property=\"og:url\" content=\"https:\/\/first.global\/fr\/gsc\/\" \/>\n<meta property=\"og:site_name\" content=\"FIRST Global\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/F1RSTglobal\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-24T20:28:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/eadn-wc05-4108819.nxedge.io\/wp-content\/uploads\/2021\/02\/Cameroon-robot-kit-dark--e1613580311298.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1601\" \/>\n\t<meta property=\"og:image:height\" content=\"892\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@F1RSTglobal\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/first.global\\\/gsc\\\/\",\"url\":\"https:\\\/\\\/first.global\\\/gsc\\\/\",\"name\":\"Global STEM Corps - FIRST Global\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/first.global\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/first.global\\\/gsc\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/first.global\\\/gsc\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/first.global\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/Cameroon-robot-kit-dark--e1613580311298.jpg?fit=1601%2C892&ssl=1\",\"datePublished\":\"2017-11-02T20:35:09+00:00\",\"dateModified\":\"2026-04-24T20:28:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/first.global\\\/gsc\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/first.global\\\/gsc\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/first.global\\\/gsc\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/first.global\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/Cameroon-robot-kit-dark--e1613580311298.jpg?fit=1601%2C892&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/first.global\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/Cameroon-robot-kit-dark--e1613580311298.jpg?fit=1601%2C892&ssl=1\",\"width\":1601,\"height\":892},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/first.global\\\/gsc\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/first.global\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Global STEM Corps\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/first.global\\\/#website\",\"url\":\"https:\\\/\\\/first.global\\\/\",\"name\":\"FIRST Global\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/first.global\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/first.global\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/first.global\\\/#organization\",\"name\":\"FIRST Global\",\"url\":\"https:\\\/\\\/first.global\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/first.global\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/first.global\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/FG_Logo-black.png?fit=4656%2C1267&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/first.global\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/FG_Logo-black.png?fit=4656%2C1267&ssl=1\",\"width\":4656,\"height\":1267,\"caption\":\"FIRST Global\"},\"image\":{\"@id\":\"https:\\\/\\\/first.global\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/F1RSTglobal\",\"https:\\\/\\\/x.com\\\/F1RSTglobal\",\"http:\\\/\\\/instagram.com\\\/f1rstglobal\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/f1rst-global\",\"http:\\\/\\\/youtube.com\\\/@f1rstglobal\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Global STEM Corps - FIRST Global","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/first.global\/fr\/gsc\/","og_locale":"fr_FR","og_type":"article","og_title":"Global STEM Corps - FIRST Global","og_url":"https:\/\/first.global\/fr\/gsc\/","og_site_name":"FIRST Global","article_publisher":"http:\/\/facebook.com\/F1RSTglobal","article_modified_time":"2026-04-24T20:28:46+00:00","og_image":[{"width":1601,"height":892,"url":"https:\/\/eadn-wc05-4108819.nxedge.io\/wp-content\/uploads\/2021\/02\/Cameroon-robot-kit-dark--e1613580311298.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@F1RSTglobal","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/first.global\/gsc\/","url":"https:\/\/first.global\/gsc\/","name":"Global STEM Corps - FIRST Global","isPartOf":{"@id":"https:\/\/first.global\/#website"},"primaryImageOfPage":{"@id":"https:\/\/first.global\/gsc\/#primaryimage"},"image":{"@id":"https:\/\/first.global\/gsc\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/first.global\/wp-content\/uploads\/2021\/02\/Cameroon-robot-kit-dark--e1613580311298.jpg?fit=1601%2C892&ssl=1","datePublished":"2017-11-02T20:35:09+00:00","dateModified":"2026-04-24T20:28:46+00:00","breadcrumb":{"@id":"https:\/\/first.global\/gsc\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/first.global\/gsc\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/first.global\/gsc\/#primaryimage","url":"https:\/\/i0.wp.com\/first.global\/wp-content\/uploads\/2021\/02\/Cameroon-robot-kit-dark--e1613580311298.jpg?fit=1601%2C892&ssl=1","contentUrl":"https:\/\/i0.wp.com\/first.global\/wp-content\/uploads\/2021\/02\/Cameroon-robot-kit-dark--e1613580311298.jpg?fit=1601%2C892&ssl=1","width":1601,"height":892},{"@type":"BreadcrumbList","@id":"https:\/\/first.global\/gsc\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/first.global\/"},{"@type":"ListItem","position":2,"name":"Global STEM Corps"}]},{"@type":"WebSite","@id":"https:\/\/first.global\/#website","url":"https:\/\/first.global\/","name":"FIRST Global","description":"","publisher":{"@id":"https:\/\/first.global\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/first.global\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/first.global\/#organization","name":"FIRST Global","url":"https:\/\/first.global\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/first.global\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/first.global\/wp-content\/uploads\/2017\/10\/FG_Logo-black.png?fit=4656%2C1267&ssl=1","contentUrl":"https:\/\/i0.wp.com\/first.global\/wp-content\/uploads\/2017\/10\/FG_Logo-black.png?fit=4656%2C1267&ssl=1","width":4656,"height":1267,"caption":"FIRST Global"},"image":{"@id":"https:\/\/first.global\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/F1RSTglobal","https:\/\/x.com\/F1RSTglobal","http:\/\/instagram.com\/f1rstglobal","https:\/\/www.linkedin.com\/company\/f1rst-global","http:\/\/youtube.com\/@f1rstglobal"]}]}},"campaignId":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/P9kXwL-4fy","jetpack-related-posts":[{"id":16568,"url":"https:\/\/first.global\/fr\/faq\/","url_meta":{"origin":16340,"position":0},"title":"FAQ","author":"FIRST Global","date":"novembre 17, 2017","format":false,"excerpt":"","rel":"","context":"Article similaire","block_context":{"text":"Article similaire","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":31565,"url":"https:\/\/first.global\/fr\/roboco\/","url_meta":{"origin":16340,"position":1},"title":"RoboCo","author":"FIRST Global","date":"mai 13, 2022","format":false,"excerpt":"","rel":"","context":"Article similaire","block_context":{"text":"Article similaire","link":""},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/first.global\/wp-content\/uploads\/2022\/05\/roboco-wLogos.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/first.global\/wp-content\/uploads\/2022\/05\/roboco-wLogos.jpg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/first.global\/wp-content\/uploads\/2022\/05\/roboco-wLogos.jpg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/first.global\/wp-content\/uploads\/2022\/05\/roboco-wLogos.jpg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/first.global\/wp-content\/uploads\/2022\/05\/roboco-wLogos.jpg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":28895,"url":"https:\/\/first.global\/fr\/archive\/fgc-2020\/","url_meta":{"origin":16340,"position":2},"title":"2020 FIRST Global Challenge","author":"FIRST Global","date":"avril 2, 2021","format":false,"excerpt":"","rel":"","context":"Article similaire","block_context":{"text":"Article similaire","link":""},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/first.global\/wp-content\/uploads\/2020\/08\/FGC2020-global-portrait-scaled-e1623355704328.jpg?fit=1200%2C756&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/first.global\/wp-content\/uploads\/2020\/08\/FGC2020-global-portrait-scaled-e1623355704328.jpg?fit=1200%2C756&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/first.global\/wp-content\/uploads\/2020\/08\/FGC2020-global-portrait-scaled-e1623355704328.jpg?fit=1200%2C756&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/first.global\/wp-content\/uploads\/2020\/08\/FGC2020-global-portrait-scaled-e1623355704328.jpg?fit=1200%2C756&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/first.global\/wp-content\/uploads\/2020\/08\/FGC2020-global-portrait-scaled-e1623355704328.jpg?fit=1200%2C756&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":16330,"url":"https:\/\/first.global\/fr\/get-involved\/","url_meta":{"origin":16340,"position":3},"title":"\u00catre Impliqu\u00e9","author":"FIRST Global","date":"novembre 2, 2017","format":false,"excerpt":"","rel":"","context":"Article similaire","block_context":{"text":"Article similaire","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":7,"url":"https:\/\/first.global\/fr\/","url_meta":{"origin":16340,"position":4},"title":"Accueil","author":"FIRST Global","date":"octobre 23, 2017","format":false,"excerpt":"","rel":"","context":"Article similaire","block_context":{"text":"Article similaire","link":""},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/first.global\/wp-content\/uploads\/2025\/02\/DJI_20240926204032_0224_D-scaled.jpeg?fit=1200%2C899&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/first.global\/wp-content\/uploads\/2025\/02\/DJI_20240926204032_0224_D-scaled.jpeg?fit=1200%2C899&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/first.global\/wp-content\/uploads\/2025\/02\/DJI_20240926204032_0224_D-scaled.jpeg?fit=1200%2C899&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/first.global\/wp-content\/uploads\/2025\/02\/DJI_20240926204032_0224_D-scaled.jpeg?fit=1200%2C899&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/first.global\/wp-content\/uploads\/2025\/02\/DJI_20240926204032_0224_D-scaled.jpeg?fit=1200%2C899&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":20103,"url":"https:\/\/first.global\/fr\/archive\/fgc-2018\/","url_meta":{"origin":16340,"position":5},"title":"D\u00e9fi mondial FIRST 2018","author":"FIRST Global","date":"septembre 11, 2018","format":false,"excerpt":"","rel":"","context":"Article similaire","block_context":{"text":"Article similaire","link":""},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/first.global\/wp-content\/uploads\/2021\/03\/AGOL3094edit.jpg?fit=1200%2C705&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/first.global\/wp-content\/uploads\/2021\/03\/AGOL3094edit.jpg?fit=1200%2C705&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/first.global\/wp-content\/uploads\/2021\/03\/AGOL3094edit.jpg?fit=1200%2C705&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/first.global\/wp-content\/uploads\/2021\/03\/AGOL3094edit.jpg?fit=1200%2C705&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/first.global\/wp-content\/uploads\/2021\/03\/AGOL3094edit.jpg?fit=1200%2C705&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/first.global\/fr\/wp-json\/wp\/v2\/pages\/16340","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/first.global\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/first.global\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/first.global\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/first.global\/fr\/wp-json\/wp\/v2\/comments?post=16340"}],"version-history":[{"count":29,"href":"https:\/\/first.global\/fr\/wp-json\/wp\/v2\/pages\/16340\/revisions"}],"predecessor-version":[{"id":115779,"href":"https:\/\/first.global\/fr\/wp-json\/wp\/v2\/pages\/16340\/revisions\/115779"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/first.global\/fr\/wp-json\/wp\/v2\/media\/28637"}],"wp:attachment":[{"href":"https:\/\/first.global\/fr\/wp-json\/wp\/v2\/media?parent=16340"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}