{"id":28321,"date":"2020-11-02T09:39:10","date_gmt":"2020-11-02T14:39:10","guid":{"rendered":"https:\/\/first.global\/?p=28321"},"modified":"2020-12-15T10:37:43","modified_gmt":"2020-12-15T15:37:43","slug":"first-global-connecting-the-worlds-youth-during-the-pandemic","status":"publish","type":"post","link":"https:\/\/first.global\/fr\/press-releases\/first-global-connecting-the-worlds-youth-during-the-pandemic\/","title":{"rendered":"FIRST Global - Connecter les jeunes du monde entier pendant la pand\u00e9mie"},"content":{"rendered":"<p><em>FIRST<\/em>\u00a0Global est une petite organisation \u00e0 but non lucratif qui a trouv\u00e9 le moyen de relier le monde de mani\u00e8re \u00e9norme et positive \u00e0 une \u00e9poque o\u00f9 les r\u00e9ponses \u00e0 la pand\u00e9mie de COVID-19 exigeaient distanciation et isolement. \u00c0 une \u00e9poque o\u00f9 de nombreuses nations se repliaient sur elles-m\u00eames,\u00a0<em>FIRST<\/em>\u00a0Global a trouv\u00e9 de nouveaux moyens pour que plus d'un millier de dirigeants de demain puissent communiquer, coop\u00e9rer et travailler ensemble.<\/p>\n<p>\u00c0 l'heure o\u00f9 nous r\u00e9fl\u00e9chissons collectivement aux \u00e9v\u00e9nements de 2020 et o\u00f9 nous d\u00e9couvrons tant d'histoires bouleversantes,\u00a0<em>FIRST<\/em>\u00a0Global apporte une lumi\u00e8re qui inspire et rassure sur le fait qu'il y a beaucoup de bonnes choses qui se passent dans le monde.<\/p>\n<p>\"Malheureusement, les probl\u00e8mes ne manquent pas dans le monde, mais heureusement, l'innovation ne manque pas non plus. Tout ce qu'il faut faire, c'est relier les deux et concentrer l'\u00e9nergie de la cr\u00e9ativit\u00e9 sur la r\u00e9solution de ces probl\u00e8mes, et c'est ce que j'esp\u00e8re que nous pourrons faire \u00e0 XPRIZE, avec les communaut\u00e9s que nous cr\u00e9ons et avec des partenaires tels que la Banque europ\u00e9enne d'investissement. <em>FIRST<\/em> Global\". - Anousheh Ansari, premi\u00e8re femme exploratrice de l'espace priv\u00e9, PDG de XPRIZE, et <em>FIRST<\/em> Membre mondial<\/p>\n<p>Comme pour beaucoup d'autres organisations, la propagation mondiale du COVID-19 a fait de l'Union europ\u00e9enne un acteur majeur de la lutte contre les maladies infectieuses.\u00a0<em>FIRST<\/em>\u00a0Global de repenser la mani\u00e8re dont ils peuvent atteindre leur objectif - rendre la science et la technologie accessibles aux jeunes du monde entier. Dans l'impossibilit\u00e9 d'organiser une comp\u00e9tition de robotique de type olympique en personne cette ann\u00e9e, ils ont cr\u00e9\u00e9 une s\u00e9rie virtuelle de d\u00e9fis techniques et de m\u00e9dias sociaux, de conf\u00e9rences sur les STIM et de ressources \u00e9ducatives afin de maintenir l'enthousiasme autour de leur programme - et cela a fonctionn\u00e9 !<\/p>\n<p>Ils ont re\u00e7u l'engagement de 175 \u00e9quipes nationales, dont une repr\u00e9sentant les r\u00e9fugi\u00e9s, de participer \u00e0 la comp\u00e9tition de 2020.\u00a0<em>FIRST<\/em>\u00a0D\u00e9fi mondial. De juillet \u00e0 septembre, des \u00e9l\u00e8ves du monde entier se sont connect\u00e9s les uns aux autres et ont montr\u00e9 que non seulement ils ont le pouvoir de vaincre, mais qu'ils sont pr\u00eats \u00e0 devenir l'avenir dont nous avons besoin pour r\u00e9soudre les plus grands d\u00e9fis du monde.<\/p>\n<p>L'un des nombreux exemples de ce type est celui des \u00e9tudiants qui ont combin\u00e9 leurs voix dans une vid\u00e9o intitul\u00e9e <a href=\"https:\/\/www.youtube.com\/watch?v=_S-RTbX_kus\">Nous sommes la g\u00e9n\u00e9ration<\/a>. Dans une autre vid\u00e9o, les \u00e9quipes ont chacune cr\u00e9\u00e9 une partie d'un m\u00e9canisme inspir\u00e9 de Rube Goldberg qui, une fois combin\u00e9e, produit une <a href=\"https:\/\/www.youtube.com\/watch?v=QiAT5AY4T3Y\">Glorieuse machine \u00e0 mouvement global<\/a> qui relie le monde entier.<\/p>\n<h4>\"Qu'est-ce que <em>FIRST<\/em> Global essaie de dire \u00e0 tous ces enfants qui imaginent des solutions fantastiques aux probl\u00e8mes et un monde meilleur : \"Apportez votre imagination, votre enthousiasme et votre vision de l'avenir, et nous vous apporterons les outils n\u00e9cessaires pour en faire une r\u00e9alit\u00e9\". - Dean Kamen, <em>FIRST<\/em> Fondateur mondial<\/h4>\n<div class=\"separator  transparent center\" style=\"height: 2px;\"><\/div>\n<p>La saison s'est achev\u00e9e le 31 octobre par une c\u00e9l\u00e9bration des r\u00e9alisations et une r\u00e9capitulation des d\u00e9fis. Vous pouvez consulter la\u00a0<a href=\"https:\/\/www.facebook.com\/F1RSTglobal\/videos\/744338196159233\/\">bobine de sizzle<\/a>\u00a0de l'\u00e9v\u00e9nement de cl\u00f4ture et de la\u00a0<a href=\"https:\/\/www.youtube.com\/watch?v=nYpyTLsTD4c\">c\u00e9l\u00e9bration compl\u00e8te de trois heures<\/a>.<\/p>\n<p>Tous ces contenus t\u00e9moignent de l'incroyable engagement des quatre derniers mois,\u00a0<em>FIRST<\/em>\u00a0Global est un ph\u00e9nom\u00e8ne qui s'\u00e9tend sur toute l'ann\u00e9e, car les \u00e9tudiants continuent d'apprendre, de se d\u00e9velopper et de mettre en place des initiatives STEM dans leurs communaut\u00e9s. De nombreuses \u00e9quipes \u00e9tendent leur impact en poursuivant leurs efforts en mati\u00e8re d'\u00e9ducation et de sensibilisation.<\/p>\n<p>Nous devons cr\u00e9er une g\u00e9n\u00e9ration mondiale qui travaille ensemble pour construire l'avenir. En montrant au monde que c'est possible,\u00a0<em>FIRST<\/em>\u00a0Global peut continuer \u00e0 inspirer les acteurs du changement qui serviront de catalyseurs, d\u00e9veloppant leur impact de mani\u00e8re exponentielle dans le monde entier et cr\u00e9ant un avenir meilleur pour tous.<\/p>\n<p>\"L'\u00e8re actuelle est celle du r\u00eaveur. C'est l'\u00e8re de celui qui r\u00e9sout les probl\u00e8mes. Le monde est en train de se transformer, que cela nous plaise ou non. Et nous pourrions attendre que quelqu'un d'autre le con\u00e7oive pour nous, ou bien les jeunes - vous - pourraient se pr\u00e9parer \u00e0 \u00eatre les architectes de demain.\" - will.i.am, musicien, entrepreneur technologique, philanthrope, et <em>FIRST<\/em> Membre mondial<\/p>\n<p>Pour plus d'informations sur la saison, le parcours et les r\u00e9alisations des \u00e9l\u00e8ves, consultez le site suivant <a href=\"\/cc\/\">premier.global\/cc\/<\/a>.<\/p>\n<p><b>\u00c0 PROPOS <i>FIRST<\/i> GLOBAL<br class=\"dnr\" \/><\/b><i>FIRST\u00a0<\/i>Global a pour mission d'inspirer le leadership et l'innovation scientifiques et technologiques chez les jeunes de toutes les nations afin d'accro\u00eetre la compr\u00e9hension, d'instiller l'importance de la coop\u00e9ration, de s'attaquer aux probl\u00e8mes les plus urgents du monde et d'am\u00e9liorer la qualit\u00e9 de vie de tous. En montrant aux jeunes du monde entier que s'ils communiquent, coop\u00e8rent et travaillent ensemble - m\u00eame dans le cadre d'une comp\u00e9tition - en utilisant les outils de la science et de l'ing\u00e9nierie pour trouver des solutions aux plus grands d\u00e9fis du monde, ils pourront accomplir de grandes choses et faire partie d'une communaut\u00e9 v\u00e9ritablement mondiale.<\/p>\n\n\t<div class=\"wpb_video_widget wpb_content_element vc_clearfix   vc_video-aspect-ratio-169 vc_video-el-width-100 vc_video-align-left\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n\t\t\t<div class=\"wpb_video_wrapper\"><span class=\"embed-youtube\" style=\"text-align:center; display: block;\"><iframe loading=\"lazy\" class=\"youtube-player\" width=\"1060\" height=\"597\" src=\"https:\/\/www.youtube.com\/embed\/_S-RTbX_kus?version=3&#038;rel=1&#038;showsearch=0&#038;showinfo=1&#038;iv_load_policy=1&#038;fs=1&#038;hl=fr-FR&#038;autohide=2&#038;wmode=transparent\" allowfullscreen=\"true\" style=\"border:0;\" sandbox=\"allow-scripts allow-same-origin allow-popups allow-presentation allow-popups-to-escape-sandbox\"><\/iframe><\/span><\/div>\n\t\t<\/div>\n\t<\/div>","protected":false},"excerpt":{"rendered":"<p>FIRST Global est une petite organisation \u00e0 but non lucratif qui a trouv\u00e9 un moyen de relier le monde de mani\u00e8re \u00e9norme et positive \u00e0 une \u00e9poque o\u00f9 les r\u00e9ponses \u00e0 la pand\u00e9mie de COVID-19 exigeaient la distanciation et l'isolement. Alors que de nombreuses nations se repliaient sur elles-m\u00eames, FIRST Global a trouv\u00e9 de nouveaux moyens pour...<\/p>","protected":false},"author":1,"featured_media":26900,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"give_campaign_id":0,"_crdt_document":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[120],"tags":[],"class_list":["post-28321","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-press-releases"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>FIRST Global - Connecting the World&#039;s Youth During the Pandemic - FIRST Global<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/first.global\/fr\/press-releases\/first-global-connecting-the-worlds-youth-during-the-pandemic\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"FIRST Global - Connecting the World&#039;s Youth During the Pandemic - FIRST Global\" \/>\n<meta property=\"og:description\" content=\"FIRST\u00a0Global is a small not-for-profit organization that found a way to connect the world in huge and positive ways during a time when responses to the COVID-19 pandemic required distancing and isolation. When many nations were looking inward,\u00a0FIRST\u00a0Global was finding new ways for 1,000+ of...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/first.global\/fr\/press-releases\/first-global-connecting-the-worlds-youth-during-the-pandemic\/\" \/>\n<meta property=\"og:site_name\" content=\"FIRST Global\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/F1RSTglobal\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-02T14:39:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-12-15T15:37:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/first.global\/wp-content\/uploads\/2020\/08\/FGC2020-global-portrait-scaled-e1623355704328.jpg?fit=1925%2C1212&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1925\" \/>\n\t<meta property=\"og:image:height\" content=\"1212\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"FIRST Global\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@F1RSTglobal\" \/>\n<meta name=\"twitter:site\" content=\"@F1RSTglobal\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"FIRST Global\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/first.global\\\/es\\\/press-releases\\\/first-global-connecting-the-worlds-youth-during-the-pandemic\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/first.global\\\/es\\\/press-releases\\\/first-global-connecting-the-worlds-youth-during-the-pandemic\\\/\"},\"author\":{\"name\":\"FIRST Global\",\"@id\":\"https:\\\/\\\/first.global\\\/#\\\/schema\\\/person\\\/7a371703b2abca02395e4f1373f522ab\"},\"headline\":\"FIRST Global &#8211; Connecting the World&#8217;s Youth During the Pandemic\",\"datePublished\":\"2020-11-02T14:39:10+00:00\",\"dateModified\":\"2020-12-15T15:37:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/first.global\\\/es\\\/press-releases\\\/first-global-connecting-the-worlds-youth-during-the-pandemic\\\/\"},\"wordCount\":748,\"publisher\":{\"@id\":\"https:\\\/\\\/first.global\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/first.global\\\/es\\\/press-releases\\\/first-global-connecting-the-worlds-youth-during-the-pandemic\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/first.global\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/FGC2020-global-portrait-scaled-e1623355704328.jpg?fit=1925%2C1212&ssl=1\",\"articleSection\":[\"Press Releases\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/first.global\\\/es\\\/press-releases\\\/first-global-connecting-the-worlds-youth-during-the-pandemic\\\/\",\"url\":\"https:\\\/\\\/first.global\\\/es\\\/press-releases\\\/first-global-connecting-the-worlds-youth-during-the-pandemic\\\/\",\"name\":\"FIRST Global - Connecting the World's Youth During the Pandemic - FIRST Global\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/first.global\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/first.global\\\/es\\\/press-releases\\\/first-global-connecting-the-worlds-youth-during-the-pandemic\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/first.global\\\/es\\\/press-releases\\\/first-global-connecting-the-worlds-youth-during-the-pandemic\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/first.global\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/FGC2020-global-portrait-scaled-e1623355704328.jpg?fit=1925%2C1212&ssl=1\",\"datePublished\":\"2020-11-02T14:39:10+00:00\",\"dateModified\":\"2020-12-15T15:37:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/first.global\\\/es\\\/press-releases\\\/first-global-connecting-the-worlds-youth-during-the-pandemic\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/first.global\\\/es\\\/press-releases\\\/first-global-connecting-the-worlds-youth-during-the-pandemic\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/first.global\\\/es\\\/press-releases\\\/first-global-connecting-the-worlds-youth-during-the-pandemic\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/first.global\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/FGC2020-global-portrait-scaled-e1623355704328.jpg?fit=1925%2C1212&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/first.global\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/FGC2020-global-portrait-scaled-e1623355704328.jpg?fit=1925%2C1212&ssl=1\",\"width\":1925,\"height\":1212},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/first.global\\\/es\\\/press-releases\\\/first-global-connecting-the-worlds-youth-during-the-pandemic\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/first.global\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"FIRST Global &#8211; Connecting the World&#8217;s Youth During the Pandemic\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/first.global\\\/#website\",\"url\":\"https:\\\/\\\/first.global\\\/\",\"name\":\"FIRST Global\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/first.global\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/first.global\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/first.global\\\/#organization\",\"name\":\"FIRST Global\",\"url\":\"https:\\\/\\\/first.global\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/first.global\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/first.global\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/FG_Logo-black.png?fit=4656%2C1267&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/first.global\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/FG_Logo-black.png?fit=4656%2C1267&ssl=1\",\"width\":4656,\"height\":1267,\"caption\":\"FIRST Global\"},\"image\":{\"@id\":\"https:\\\/\\\/first.global\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/F1RSTglobal\",\"https:\\\/\\\/x.com\\\/F1RSTglobal\",\"http:\\\/\\\/instagram.com\\\/f1rstglobal\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/f1rst-global\",\"http:\\\/\\\/youtube.com\\\/@f1rstglobal\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/first.global\\\/#\\\/schema\\\/person\\\/7a371703b2abca02395e4f1373f522ab\",\"name\":\"FIRST Global\",\"url\":\"https:\\\/\\\/first.global\\\/fr\\\/author\\\/khadijah\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"FIRST Global - Connecter les jeunes du monde entier pendant la pand\u00e9mie - FIRST Global","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/first.global\/fr\/press-releases\/first-global-connecting-the-worlds-youth-during-the-pandemic\/","og_locale":"fr_FR","og_type":"article","og_title":"FIRST Global - Connecting the World's Youth During the Pandemic - FIRST Global","og_description":"FIRST\u00a0Global is a small not-for-profit organization that found a way to connect the world in huge and positive ways during a time when responses to the COVID-19 pandemic required distancing and isolation. When many nations were looking inward,\u00a0FIRST\u00a0Global was finding new ways for 1,000+ of...","og_url":"https:\/\/first.global\/fr\/press-releases\/first-global-connecting-the-worlds-youth-during-the-pandemic\/","og_site_name":"FIRST Global","article_publisher":"http:\/\/facebook.com\/F1RSTglobal","article_published_time":"2020-11-02T14:39:10+00:00","article_modified_time":"2020-12-15T15:37:43+00:00","og_image":[{"width":1925,"height":1212,"url":"https:\/\/i0.wp.com\/first.global\/wp-content\/uploads\/2020\/08\/FGC2020-global-portrait-scaled-e1623355704328.jpg?fit=1925%2C1212&ssl=1","type":"image\/jpeg"}],"author":"FIRST Global","twitter_card":"summary_large_image","twitter_creator":"@F1RSTglobal","twitter_site":"@F1RSTglobal","twitter_misc":{"\u00c9crit par":"FIRST Global","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/first.global\/es\/press-releases\/first-global-connecting-the-worlds-youth-during-the-pandemic\/#article","isPartOf":{"@id":"https:\/\/first.global\/es\/press-releases\/first-global-connecting-the-worlds-youth-during-the-pandemic\/"},"author":{"name":"FIRST Global","@id":"https:\/\/first.global\/#\/schema\/person\/7a371703b2abca02395e4f1373f522ab"},"headline":"FIRST Global &#8211; Connecting the World&#8217;s Youth During the Pandemic","datePublished":"2020-11-02T14:39:10+00:00","dateModified":"2020-12-15T15:37:43+00:00","mainEntityOfPage":{"@id":"https:\/\/first.global\/es\/press-releases\/first-global-connecting-the-worlds-youth-during-the-pandemic\/"},"wordCount":748,"publisher":{"@id":"https:\/\/first.global\/#organization"},"image":{"@id":"https:\/\/first.global\/es\/press-releases\/first-global-connecting-the-worlds-youth-during-the-pandemic\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/first.global\/wp-content\/uploads\/2020\/08\/FGC2020-global-portrait-scaled-e1623355704328.jpg?fit=1925%2C1212&ssl=1","articleSection":["Press Releases"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/first.global\/es\/press-releases\/first-global-connecting-the-worlds-youth-during-the-pandemic\/","url":"https:\/\/first.global\/es\/press-releases\/first-global-connecting-the-worlds-youth-during-the-pandemic\/","name":"FIRST Global - Connecter les jeunes du monde entier pendant la pand\u00e9mie - FIRST Global","isPartOf":{"@id":"https:\/\/first.global\/#website"},"primaryImageOfPage":{"@id":"https:\/\/first.global\/es\/press-releases\/first-global-connecting-the-worlds-youth-during-the-pandemic\/#primaryimage"},"image":{"@id":"https:\/\/first.global\/es\/press-releases\/first-global-connecting-the-worlds-youth-during-the-pandemic\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/first.global\/wp-content\/uploads\/2020\/08\/FGC2020-global-portrait-scaled-e1623355704328.jpg?fit=1925%2C1212&ssl=1","datePublished":"2020-11-02T14:39:10+00:00","dateModified":"2020-12-15T15:37:43+00:00","breadcrumb":{"@id":"https:\/\/first.global\/es\/press-releases\/first-global-connecting-the-worlds-youth-during-the-pandemic\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/first.global\/es\/press-releases\/first-global-connecting-the-worlds-youth-during-the-pandemic\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/first.global\/es\/press-releases\/first-global-connecting-the-worlds-youth-during-the-pandemic\/#primaryimage","url":"https:\/\/i0.wp.com\/first.global\/wp-content\/uploads\/2020\/08\/FGC2020-global-portrait-scaled-e1623355704328.jpg?fit=1925%2C1212&ssl=1","contentUrl":"https:\/\/i0.wp.com\/first.global\/wp-content\/uploads\/2020\/08\/FGC2020-global-portrait-scaled-e1623355704328.jpg?fit=1925%2C1212&ssl=1","width":1925,"height":1212},{"@type":"BreadcrumbList","@id":"https:\/\/first.global\/es\/press-releases\/first-global-connecting-the-worlds-youth-during-the-pandemic\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/first.global\/"},{"@type":"ListItem","position":2,"name":"FIRST Global &#8211; Connecting the World&#8217;s Youth During the Pandemic"}]},{"@type":"WebSite","@id":"https:\/\/first.global\/#website","url":"https:\/\/first.global\/","name":"FIRST Global","description":"","publisher":{"@id":"https:\/\/first.global\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/first.global\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/first.global\/#organization","name":"FIRST Global","url":"https:\/\/first.global\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/first.global\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/first.global\/wp-content\/uploads\/2017\/10\/FG_Logo-black.png?fit=4656%2C1267&ssl=1","contentUrl":"https:\/\/i0.wp.com\/first.global\/wp-content\/uploads\/2017\/10\/FG_Logo-black.png?fit=4656%2C1267&ssl=1","width":4656,"height":1267,"caption":"FIRST Global"},"image":{"@id":"https:\/\/first.global\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/F1RSTglobal","https:\/\/x.com\/F1RSTglobal","http:\/\/instagram.com\/f1rstglobal","https:\/\/www.linkedin.com\/company\/f1rst-global","http:\/\/youtube.com\/@f1rstglobal"]},{"@type":"Person","@id":"https:\/\/first.global\/#\/schema\/person\/7a371703b2abca02395e4f1373f522ab","name":"FIRST Global","url":"https:\/\/first.global\/fr\/author\/khadijah\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/first.global\/wp-content\/uploads\/2020\/08\/FGC2020-global-portrait-scaled-e1623355704328.jpg?fit=1925%2C1212&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9kXwL-7mN","jetpack-related-posts":[{"id":24231,"url":"https:\/\/first.global\/fr\/in-the-news\/all-girl-afghan-robotic-team-tries-to-build-cheap-ventilators-to-help-covid-19-patients\/","url_meta":{"origin":28321,"position":0},"title":"Une \u00e9quipe de robotique afghane compos\u00e9e uniquement de filles tente de construire des ventilateurs bon march\u00e9 pour aider les patients atteints de la maladie COVID-19","author":"FIRST Global","date":"avril 27, 2020","format":false,"excerpt":"KABOUL, 26 avril (Xinhua) -- Une \u00e9quipe de six jeunes filles afghanes, r\u00e9compens\u00e9e lors d'un concours international de robotique, a commenc\u00e9 \u00e0 construire des ventilateurs \u00e0 bas prix, alors que la pand\u00e9mie de coronavirus est en hausse dans le pays. \"Le monde est confront\u00e9 \u00e0 une crise sanitaire. Le monde souffre d'une p\u00e9nurie...","rel":"","context":"Dans &quot;In the News&quot;","block_context":{"text":"In the News","link":"https:\/\/first.global\/fr\/category\/in-the-news\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/images.china.cn\/images1\/en\/2009home\/logo.gif?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":30264,"url":"https:\/\/first.global\/fr\/press-releases\/fgc-2021-launch\/","url_meta":{"origin":28321,"position":1},"title":"FIRST Global r\u00e9unit les lyc\u00e9ens de plus de 160 pays pour r\u00e9soudre les d\u00e9fis mondiaux pos\u00e9s par la pand\u00e9mie.","author":"FIRST Global","date":"juin 27, 2021","format":"video","excerpt":"Du 27 juin au 28 septembre, les jeunes travailleront ensemble dans le cadre du FIRST Global Challenge, innovant des solutions pour renforcer leurs communaut\u00e9s gr\u00e2ce aux STIM 27 juin 2021 MANCHESTER, N.H. - Des projets sociaux aux satellites miniatures en passant par la conception de robots, l'organisation \u00e0 but non lucratif FIRST Global lance sa derni\u00e8re saison pour les adolescents de...","rel":"","context":"Dans &quot;Press Releases&quot;","block_context":{"text":"Press Releases","link":"https:\/\/first.global\/fr\/category\/press-releases\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/first.global\/wp-content\/uploads\/2021\/06\/FGC2021DR.jpeg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/first.global\/wp-content\/uploads\/2021\/06\/FGC2021DR.jpeg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/first.global\/wp-content\/uploads\/2021\/06\/FGC2021DR.jpeg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/first.global\/wp-content\/uploads\/2021\/06\/FGC2021DR.jpeg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/first.global\/wp-content\/uploads\/2021\/06\/FGC2021DR.jpeg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":33034,"url":"https:\/\/first.global\/fr\/2022-nations\/honduras-2022\/","url_meta":{"origin":28321,"position":2},"title":"\u00c9quipe Honduras 2022 \ud83c\udded\ud83c\uddf3","author":"FIRST Global","date":"mai 26, 2022","format":false,"excerpt":"Clause de non-responsabilit\u00e9 : Le langage, les opinions et les images affich\u00e9s sur cette page de profil d'\u00e9quipe sont ceux de cette \u00e9quipe et ne refl\u00e8tent pas n\u00e9cessairement les points de vue ou les positions de FIRST Global.","rel":"","context":"Dans &quot;2022 Nations&quot;","block_context":{"text":"2022 Nations","link":"https:\/\/first.global\/fr\/category\/2022-nations\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/first.global\/wp-content\/uploads\/2024\/11\/Honduras-2022.jpeg?fit=960%2C720&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/first.global\/wp-content\/uploads\/2024\/11\/Honduras-2022.jpeg?fit=960%2C720&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/first.global\/wp-content\/uploads\/2024\/11\/Honduras-2022.jpeg?fit=960%2C720&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/first.global\/wp-content\/uploads\/2024\/11\/Honduras-2022.jpeg?fit=960%2C720&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":30456,"url":"https:\/\/first.global\/fr\/2021-nations\/honduras-2021\/","url_meta":{"origin":28321,"position":3},"title":"\u00c9quipe Honduras 2021 \ud83c\udded\ud83c\uddf3","author":"FIRST Global","date":"ao\u00fbt 11, 2021","format":false,"excerpt":"","rel":"","context":"Dans &quot;2021 Nations&quot;","block_context":{"text":"2021 Nations","link":"https:\/\/first.global\/fr\/category\/2021-nations\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/first.global\/wp-content\/uploads\/2021\/08\/Honduras-2021.jpg?fit=1112%2C850&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/first.global\/wp-content\/uploads\/2021\/08\/Honduras-2021.jpg?fit=1112%2C850&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/first.global\/wp-content\/uploads\/2021\/08\/Honduras-2021.jpg?fit=1112%2C850&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/first.global\/wp-content\/uploads\/2021\/08\/Honduras-2021.jpg?fit=1112%2C850&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/first.global\/wp-content\/uploads\/2021\/08\/Honduras-2021.jpg?fit=1112%2C850&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":27217,"url":"https:\/\/first.global\/fr\/in-the-news\/federations-robotics-team-competes-in-first-global-challenge\/","url_meta":{"origin":28321,"position":4},"title":"L'\u00e9quipe de robotique de la F\u00e9d\u00e9ration participe au FIRST Global Challenge","author":"FIRST Global","date":"juillet 22, 2020","format":false,"excerpt":"BASSETERRE, Saint-Kitts - L'\u00e9quipe de robotique de Saint-Kitts-et-Nevis participe \u00e0 l'\u00e9dition 2020 du FIRST Global Challenge - Connecting Communities, qui se d\u00e9roule du 1er juillet au 26 septembre. L'\u00e9v\u00e9nement sera virtuel en raison de la pand\u00e9mie de COVID-19. \"La situation du COVID-19 a chang\u00e9 toute la dynamique de nos d\u00e9placements, nous sommes donc en ligne...","rel":"","context":"Dans &quot;In the News&quot;","block_context":{"text":"In the News","link":"https:\/\/first.global\/fr\/category\/in-the-news\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/first.global\/wp-content\/uploads\/2020\/07\/Saint-Kitts-_-Nevis-2020-Say-Cheese-Image.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/first.global\/wp-content\/uploads\/2020\/07\/Saint-Kitts-_-Nevis-2020-Say-Cheese-Image.jpg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/first.global\/wp-content\/uploads\/2020\/07\/Saint-Kitts-_-Nevis-2020-Say-Cheese-Image.jpg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/first.global\/wp-content\/uploads\/2020\/07\/Saint-Kitts-_-Nevis-2020-Say-Cheese-Image.jpg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/first.global\/wp-content\/uploads\/2020\/07\/Saint-Kitts-_-Nevis-2020-Say-Cheese-Image.jpg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":31336,"url":"https:\/\/first.global\/fr\/in-the-news\/the-messi-of-robotics-are-from-la-rioja-and-designed-a-platform-to-study-during-the-pandemic\/","url_meta":{"origin":28321,"position":5},"title":"Les Messi de la robotique sont originaires de La Rioja et ont con\u00e7u une plateforme pour \u00e9tudier la pand\u00e9mie.","author":"FIRST Global","date":"novembre 30, 2021","format":false,"excerpt":"(Cinq \u00e9l\u00e8ves d'une \u00e9cole secondaire de cette province ont repr\u00e9sent\u00e9 le pays \u00e0 la Coupe du monde de robotique et sont arriv\u00e9s septi\u00e8mes au classement g\u00e9n\u00e9ral sur 176 pays. Ils ont programm\u00e9 et cr\u00e9\u00e9 des appareils pour r\u00e9soudre des probl\u00e8mes dans leur communaut\u00e9. Ils assurent que c'\u00e9tait...","rel":"","context":"Dans &quot;In the News&quot;","block_context":{"text":"In the News","link":"https:\/\/first.global\/fr\/category\/in-the-news\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/first.global\/wp-content\/uploads\/2021\/06\/Argentina-2021.jpg?fit=843%2C768&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/first.global\/wp-content\/uploads\/2021\/06\/Argentina-2021.jpg?fit=843%2C768&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/first.global\/wp-content\/uploads\/2021\/06\/Argentina-2021.jpg?fit=843%2C768&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/first.global\/wp-content\/uploads\/2021\/06\/Argentina-2021.jpg?fit=843%2C768&ssl=1&resize=700%2C400 2x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/first.global\/fr\/wp-json\/wp\/v2\/posts\/28321","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/first.global\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/first.global\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/first.global\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/first.global\/fr\/wp-json\/wp\/v2\/comments?post=28321"}],"version-history":[{"count":13,"href":"https:\/\/first.global\/fr\/wp-json\/wp\/v2\/posts\/28321\/revisions"}],"predecessor-version":[{"id":28334,"href":"https:\/\/first.global\/fr\/wp-json\/wp\/v2\/posts\/28321\/revisions\/28334"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/first.global\/fr\/wp-json\/wp\/v2\/media\/26900"}],"wp:attachment":[{"href":"https:\/\/first.global\/fr\/wp-json\/wp\/v2\/media?parent=28321"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/first.global\/fr\/wp-json\/wp\/v2\/categories?post=28321"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/first.global\/fr\/wp-json\/wp\/v2\/tags?post=28321"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}