{"id":34405,"date":"2022-12-01T15:52:07","date_gmt":"2022-12-01T20:52:07","guid":{"rendered":"https:\/\/first.global\/?p=34405"},"modified":"2024-12-21T16:00:06","modified_gmt":"2024-12-21T21:00:06","slug":"intel-partners-with-first-global-for-a-2023-student-maker-cohort-focused-on-neural-code-innovation","status":"publish","type":"post","link":"https:\/\/first.global\/fr\/press-releases\/intel-partners-with-first-global-for-a-2023-student-maker-cohort-focused-on-neural-code-innovation\/","title":{"rendered":"Intel s'associe \u00e0 FIRST Global pour une cohorte d'\u00e9tudiants Maker 2023 ax\u00e9e sur l'innovation en mati\u00e8re de code neuronal"},"content":{"rendered":"<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"34371\" data-permalink=\"https:\/\/first.global\/fr\/archive\/fgc-2022\/attachment\/intel-logo-2022\/\" data-orig-file=\"https:\/\/i0.wp.com\/first.global\/wp-content\/uploads\/2024\/12\/intel-logo-2022.png?fit=300%2C122&amp;ssl=1\" data-orig-size=\"300,122\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"intel-logo-2022\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/first.global\/wp-content\/uploads\/2024\/12\/intel-logo-2022.png?fit=300%2C122&amp;ssl=1\" class=\"alignnone wp-image-34371\" src=\"https:\/\/i0.wp.com\/first.global\/wp-content\/uploads\/2024\/12\/intel-logo-2022.png?resize=211%2C86&#038;ssl=1\" alt=\"\" width=\"211\" height=\"86\" srcset=\"https:\/\/i0.wp.com\/first.global\/wp-content\/uploads\/2024\/12\/intel-logo-2022.png?w=300&amp;ssl=1 300w, https:\/\/i0.wp.com\/first.global\/wp-content\/uploads\/2024\/12\/intel-logo-2022.png?resize=18%2C7&amp;ssl=1 18w\" sizes=\"auto, (max-width: 211px) 100vw, 211px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Pour 2023, Intel parraine une cohorte d'\u00e9tudiants makers destin\u00e9e \u00e0 cr\u00e9er une communaut\u00e9 d'apprentissage partag\u00e9 entre les leaders de l'industrie, les technologues et la prochaine g\u00e9n\u00e9ration d'\u00e9tudiants makers, qui contribueront \u00e0 l'application de l'intelligence artificielle (IA) pour l'innovation industrielle.<\/p>\n<p>En janvier 2023, Intel annoncera les d\u00e9tails de la cohorte d'\u00e9tudiants Maker qu'elle parrainera.\u00a0<em>FIRST\u00ae<\/em> Les participants du monde entier seront initi\u00e9s \u00e0 une nouvelle fa\u00e7on de d\u00e9ployer la vision par ordinateur en utilisant une technologie qui reproduit la fa\u00e7on dont la r\u00e9tine de l'\u0153il humain traite les informations visuelles. Les \u00e9tudiants auront l'occasion d'apprendre et d'utiliser cette approche r\u00e9volutionnaire mise au point par le Dr Sheila Nirenberg en appliquant ses m\u00e9rites \u00e0 la navigation torobotique.<\/p>\n<p>\"Nous sommes ravis de collaborer avec\u00a0<em>FIRST<\/em>Participants internationaux et \u00e9tudiants de la conf\u00e9rence 2022<em>FIRST<\/em>Global Challenge avec la cohorte d'\u00e9tudiants makers que nous parrainons. Gr\u00e2ce \u00e0 cette cohorte, nous pouvons faciliter l'apprentissage entre les makers de la prochaine g\u00e9n\u00e9ration tout en exposant les \u00e9tudiants \u00e0 des innovateurs de l'industrie et \u00e0 des technologues de premier plan\", a d\u00e9clar\u00e9 Stacey Shulman, vice-pr\u00e9sidente de Network and Edge, directrice g\u00e9n\u00e9rale de la division Health, Education, and Consumer Industries (sant\u00e9, \u00e9ducation et industries de consommation). \"Nous voyons le potentiel de cette nouvelle m\u00e9thode d'intelligence artificielle et cherchons \u00e0 impliquer la communaut\u00e9 \u00e9tudiante pour qu'elle apporte son point de vue et son ing\u00e9niosit\u00e9.\"<\/p>\n<p>Les \u00e9l\u00e8ves participants recevront du mat\u00e9riel suppl\u00e9mentaire pour le kit de fabrication et un calendrier de programme o\u00f9 ils s'engageront dans la r\u00e9flexion sur la conception, l'apprentissage organis\u00e9 et le mentorat. \"L'apprentissage partag\u00e9 est un \u00e9l\u00e9ment essentiel de l'innovation\", a poursuivi M. Shulman. \"Nous sommes ravis d'inclure un programme qui offre aux \u00e9tudiants la possibilit\u00e9 de rencontrer virtuellement le Dr Nirenberg, le mentorat d'ing\u00e9nieurs et de chefs d'entreprise de haut niveau, et des outils logiciels pour exp\u00e9rimenter et explorer de nouvelles fa\u00e7ons de r\u00e9soudre les probl\u00e8mes d'IA, y compris en apprenant comment la r\u00e9tine et le cerveau r\u00e9solvent des probl\u00e8mes similaires. \u00c0 la fin de la cohorte, nous esp\u00e9rons que les \u00e9tudiants auront approfondi leur compr\u00e9hension et leur application des technologies \u00e9mergentes, qu'ils auront nou\u00e9 de nouveaux liens avec la communaut\u00e9 des cr\u00e9ateurs et qu'ils auront acquis des comp\u00e9tences essentielles en mati\u00e8re de STIM qui les aideront \u00e0 progresser dans leur vie professionnelle\".<\/p>\n<p>Intel est un leader de l'industrie, cr\u00e9ant des technologies qui changent le monde, permettant le progr\u00e8s global et enrichissant les vies. La vaste gamme de blocs de construction et d'outils mat\u00e9riels et logiciels d'Intel\u00ae permet des innovations passionnantes en mati\u00e8re d'intelligence int\u00e9gr\u00e9e dans le nuage, le r\u00e9seau, la p\u00e9riph\u00e9rie et chaque appareil informatique. Ces innovations marquent une nouvelle \u00e8re pour lib\u00e9rer le potentiel des donn\u00e9es afin de transformer les entreprises et la soci\u00e9t\u00e9 pour le meilleur.<\/p>\n<p>\"Engager nos<em>FIRST<\/em>La pr\u00e9sence d'une communaut\u00e9 mondiale d'\u00e9tudiants poss\u00e9dant des technologies d'avant-garde est extr\u00eamement pr\u00e9cieuse pour notre prochaine g\u00e9n\u00e9ration d'innovateurs qui fa\u00e7onneront les industries de demain\", a d\u00e9clar\u00e9 le directeur g\u00e9n\u00e9ral de l'Institut de recherche sur les technologies de l'information.<em>FIRST<\/em>Global, Dean Kamen. \"Nous sommes heureux de collaborer avec Intel et de soutenir son intention de cr\u00e9er de nouvelles possibilit\u00e9s d'apprentissage pour les \u00e9tudiants. L'expertise unique d'Intel dans l'industrie est bien adapt\u00e9e aux besoins des \u00e9tudiants.<em>FIRST\u00a0<\/em>Global pour former les futurs leaders en mati\u00e8re de STIM\".<\/p>\n<p>&nbsp;<\/p>\n<p>Pour 2023, Intel parraine une cohorte d'\u00e9tudiants makers destin\u00e9e \u00e0 cr\u00e9er une communaut\u00e9 d'apprentissage partag\u00e9 entre les leaders de l'industrie, les technologues et la prochaine g\u00e9n\u00e9ration d'\u00e9tudiants makers, qui contribueront \u00e0 l'application de l'intelligence artificielle (IA) pour l'innovation industrielle.<\/p>\n<p>En janvier 2023, Intel annoncera les d\u00e9tails de la cohorte d'\u00e9tudiants Maker qu'elle parrainera.\u00a0<em>FIRST\u00ae<\/em>\u00a0Les participants du monde entier seront initi\u00e9s \u00e0 une nouvelle fa\u00e7on de d\u00e9ployer la vision par ordinateur en utilisant une technologie qui reproduit la fa\u00e7on dont la r\u00e9tine de l'\u0153il humain traite les informations visuelles. Les \u00e9tudiants auront l'occasion d'apprendre et d'utiliser cette approche r\u00e9volutionnaire d\u00e9velopp\u00e9e par le Dr Sheila Nirenberg en appliquant ses m\u00e9rites \u00e0 la navigation robotique.<\/p>\n<p>\"Nous sommes ravis de collaborer avec\u00a0<em>FIRST<\/em>Participants internationaux et \u00e9tudiants de la conf\u00e9rence 2022<em>FIRST<\/em>Global Challenge avec la cohorte d'\u00e9tudiants makers que nous parrainons. Gr\u00e2ce \u00e0 cette cohorte, nous pouvons faciliter l'apprentissage entre les makers de la prochaine g\u00e9n\u00e9ration tout en exposant les \u00e9tudiants \u00e0 des innovateurs de l'industrie et \u00e0 des technologues de premier plan\", a d\u00e9clar\u00e9 Stacey Shulman, vice-pr\u00e9sidente de Network and Edge, directrice g\u00e9n\u00e9rale de la division Health, Education, and Consumer Industries (sant\u00e9, \u00e9ducation et industries de consommation). \"Nous voyons le potentiel de cette nouvelle m\u00e9thode d'intelligence artificielle et cherchons \u00e0 impliquer la communaut\u00e9 \u00e9tudiante pour qu'elle apporte son point de vue et son ing\u00e9niosit\u00e9.\"<\/p>\n<p>Les \u00e9l\u00e8ves participants recevront du mat\u00e9riel suppl\u00e9mentaire pour le kit de fabrication et un calendrier de programme o\u00f9 ils s'engageront dans la r\u00e9flexion sur la conception, l'apprentissage organis\u00e9 et le mentorat. \"L'apprentissage partag\u00e9 est un \u00e9l\u00e9ment essentiel de l'innovation\", a poursuivi M. Shulman. \"Nous sommes ravis d'inclure un programme qui offre aux \u00e9tudiants la possibilit\u00e9 de rencontrer virtuellement le Dr Nirenberg, le mentorat d'ing\u00e9nieurs et de chefs d'entreprise de haut niveau, et des outils logiciels pour exp\u00e9rimenter et explorer de nouvelles fa\u00e7ons de r\u00e9soudre les probl\u00e8mes d'IA, y compris en apprenant comment la r\u00e9tine et le cerveau r\u00e9solvent des probl\u00e8mes similaires. \u00c0 la fin de la cohorte, nous esp\u00e9rons que les \u00e9tudiants auront approfondi leur compr\u00e9hension et leur application des technologies \u00e9mergentes, qu'ils auront nou\u00e9 de nouveaux liens avec la communaut\u00e9 des cr\u00e9ateurs et qu'ils auront acquis des comp\u00e9tences essentielles en mati\u00e8re de STIM qui les aideront \u00e0 progresser dans leur vie professionnelle\".<\/p>\n<p>Intel est un leader de l'industrie, cr\u00e9ant des technologies qui changent le monde, permettant le progr\u00e8s global et enrichissant les vies. La vaste gamme de blocs de construction et d'outils mat\u00e9riels et logiciels d'Intel\u00ae permet des innovations passionnantes en mati\u00e8re d'intelligence int\u00e9gr\u00e9e dans le nuage, le r\u00e9seau, la p\u00e9riph\u00e9rie et chaque appareil informatique. Ces innovations marquent une nouvelle \u00e8re pour lib\u00e9rer le potentiel des donn\u00e9es afin de transformer les entreprises et la soci\u00e9t\u00e9 pour le meilleur.<\/p>\n<p>\"Engager nos<em>FIRST<\/em>La pr\u00e9sence d'une communaut\u00e9 mondiale d'\u00e9tudiants poss\u00e9dant des technologies d'avant-garde est extr\u00eamement pr\u00e9cieuse pour notre prochaine g\u00e9n\u00e9ration d'innovateurs qui fa\u00e7onneront les industries de demain\", a d\u00e9clar\u00e9 le directeur g\u00e9n\u00e9ral de l'Institut de recherche sur les technologies de l'information.<em>FIRST<\/em>Global, Dean Kamen. \"Nous sommes heureux de collaborer avec Intel et de soutenir son intention de cr\u00e9er de nouvelles possibilit\u00e9s d'apprentissage pour les \u00e9tudiants. L'expertise unique d'Intel dans l'industrie est bien adapt\u00e9e aux besoins des \u00e9tudiants.<em>FIRST\u00a0<\/em>Global pour former les futurs leaders en mati\u00e8re de STIM\".<\/p>\n<p>Pour 2023, Intel parraine une cohorte d'\u00e9tudiants makers destin\u00e9e \u00e0 cr\u00e9er une communaut\u00e9 d'apprentissage partag\u00e9 entre les leaders de l'industrie, les technologues et la prochaine g\u00e9n\u00e9ration d'\u00e9tudiants makers, qui contribueront \u00e0 l'application de l'intelligence artificielle (IA) pour l'innovation industrielle.<\/p>\n<p>En janvier 2023, Intel annoncera les d\u00e9tails de la cohorte d'\u00e9tudiants Maker qu'elle parrainera.\u00a0<em>FIRST\u00ae<\/em>\u00a0Les participants du monde entier seront initi\u00e9s \u00e0 une nouvelle fa\u00e7on de d\u00e9ployer la vision par ordinateur en utilisant une technologie qui reproduit la fa\u00e7on dont la r\u00e9tine de l'\u0153il humain traite les informations visuelles. Les \u00e9tudiants auront l'occasion d'apprendre et d'utiliser cette approche r\u00e9volutionnaire d\u00e9velopp\u00e9e par le Dr Sheila Nirenberg en appliquant ses m\u00e9rites \u00e0 la navigation robotique.<\/p>\n<p>\"Nous sommes ravis de collaborer avec\u00a0<em>FIRST<\/em>Participants internationaux et \u00e9tudiants de la conf\u00e9rence 2022<em>FIRST<\/em>Global Challenge avec la cohorte d'\u00e9tudiants makers que nous parrainons. Gr\u00e2ce \u00e0 cette cohorte, nous pouvons faciliter l'apprentissage entre les makers de la prochaine g\u00e9n\u00e9ration tout en exposant les \u00e9tudiants \u00e0 des innovateurs de l'industrie et \u00e0 des technologues de premier plan\", a d\u00e9clar\u00e9 Stacey Shulman, vice-pr\u00e9sidente de Network and Edge, directrice g\u00e9n\u00e9rale de la division Health, Education, and Consumer Industries (sant\u00e9, \u00e9ducation et industries de consommation). \"Nous voyons le potentiel de cette nouvelle m\u00e9thode d'intelligence artificielle et cherchons \u00e0 impliquer la communaut\u00e9 \u00e9tudiante pour qu'elle apporte son point de vue et son ing\u00e9niosit\u00e9.\"<\/p>\n<p>Les \u00e9l\u00e8ves participants recevront du mat\u00e9riel suppl\u00e9mentaire pour le kit de fabrication et un calendrier de programme o\u00f9 ils s'engageront dans la r\u00e9flexion sur la conception, l'apprentissage organis\u00e9 et le mentorat. \"L'apprentissage partag\u00e9 est un \u00e9l\u00e9ment essentiel de l'innovation\", a poursuivi M. Shulman. \"Nous sommes ravis d'inclure un programme qui offre aux \u00e9tudiants la possibilit\u00e9 de rencontrer virtuellement le Dr Nirenberg, le mentorat d'ing\u00e9nieurs et de chefs d'entreprise de haut niveau, et des outils logiciels pour exp\u00e9rimenter et explorer de nouvelles fa\u00e7ons de r\u00e9soudre les probl\u00e8mes d'IA, y compris en apprenant comment la r\u00e9tine et le cerveau r\u00e9solvent des probl\u00e8mes similaires. \u00c0 la fin de la cohorte, nous esp\u00e9rons que les \u00e9tudiants auront approfondi leur compr\u00e9hension et leur application des technologies \u00e9mergentes, qu'ils auront nou\u00e9 de nouveaux liens avec la communaut\u00e9 des cr\u00e9ateurs et qu'ils auront acquis des comp\u00e9tences essentielles en mati\u00e8re de STIM qui les aideront \u00e0 progresser dans leur vie professionnelle\".<\/p>\n<p>Intel est un leader de l'industrie, cr\u00e9ant des technologies qui changent le monde, permettant le progr\u00e8s global et enrichissant les vies. La vaste gamme de blocs de construction et d'outils mat\u00e9riels et logiciels d'Intel\u00ae permet des innovations passionnantes en mati\u00e8re d'intelligence int\u00e9gr\u00e9e dans le nuage, le r\u00e9seau, la p\u00e9riph\u00e9rie et chaque appareil informatique. Ces innovations marquent une nouvelle \u00e8re pour lib\u00e9rer le potentiel des donn\u00e9es afin de transformer les entreprises et la soci\u00e9t\u00e9 pour le meilleur.<\/p>\n<p>\"Engager nos<em>FIRST<\/em>La pr\u00e9sence d'une communaut\u00e9 mondiale d'\u00e9tudiants poss\u00e9dant des technologies d'avant-garde est extr\u00eamement pr\u00e9cieuse pour notre prochaine g\u00e9n\u00e9ration d'innovateurs qui fa\u00e7onneront les industries de demain\", a d\u00e9clar\u00e9 le directeur g\u00e9n\u00e9ral de l'Institut de recherche sur les technologies de l'information.<em>FIRST<\/em>Global, Dean Kamen. \"Nous sommes heureux de collaborer avec Intel et de soutenir son intention de cr\u00e9er de nouvelles possibilit\u00e9s d'apprentissage pour les \u00e9tudiants. L'expertise unique d'Intel dans l'industrie est bien adapt\u00e9e aux besoins des \u00e9tudiants.<em>FIRST\u00a0<\/em>Global pour former les futurs leaders en mati\u00e8re de STIM\".<\/p>","protected":false},"excerpt":{"rendered":"<p>&nbsp; Pour 2023, Intel sponsorise une cohorte d'\u00e9tudiants makers destin\u00e9e \u00e0 cr\u00e9er une communaut\u00e9 d'apprentissage partag\u00e9 entre les leaders de l'industrie, les technologues et la prochaine g\u00e9n\u00e9ration d'\u00e9tudiants makers, qui contribueront \u00e0 l'application de l'Intelligence Artificielle (IA) pour l'innovation de l'industrie. En janvier 2023,...<\/p>","protected":false},"author":20,"featured_media":19788,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"give_campaign_id":0,"_crdt_document":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[120,1],"tags":[],"class_list":["post-34405","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-press-releases","category-uncategorized"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Intel partners with FIRST Global for a 2023 Student Maker Cohort focused on neural code innovation - FIRST Global<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/first.global\/fr\/press-releases\/intel-partners-with-first-global-for-a-2023-student-maker-cohort-focused-on-neural-code-innovation\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Intel partners with FIRST Global for a 2023 Student Maker Cohort focused on neural code innovation - FIRST Global\" \/>\n<meta property=\"og:description\" content=\"&nbsp; For 2023, Intel is sponsoring a Student Maker Cohort intended to create a community for shared learning between industry leaders, technologists, and the next generation of student makers, who will contribute to the application of Artificial Intelligence (AI) for industry innovation. In January 2023,...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/first.global\/fr\/press-releases\/intel-partners-with-first-global-for-a-2023-student-maker-cohort-focused-on-neural-code-innovation\/\" \/>\n<meta property=\"og:site_name\" content=\"FIRST Global\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/F1RSTglobal\" \/>\n<meta property=\"article:published_time\" content=\"2022-12-01T20:52:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-21T21:00:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/eadn-wc05-4108819.nxedge.io\/wp-content\/uploads\/2018\/08\/Intel_LOGO-2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"FIRST Global\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@F1RSTglobal\" \/>\n<meta name=\"twitter:site\" content=\"@F1RSTglobal\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"FIRST Global\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/first.global\\\/press-releases\\\/intel-partners-with-first-global-for-a-2023-student-maker-cohort-focused-on-neural-code-innovation\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/first.global\\\/press-releases\\\/intel-partners-with-first-global-for-a-2023-student-maker-cohort-focused-on-neural-code-innovation\\\/\"},\"author\":{\"name\":\"FIRST Global\",\"@id\":\"https:\\\/\\\/first.global\\\/#\\\/schema\\\/person\\\/3b3ac653fa313ed64d0ee0c119cc8f7d\"},\"headline\":\"Intel partners with FIRST Global for a 2023 Student Maker Cohort focused on neural code innovation\",\"datePublished\":\"2022-12-01T20:52:07+00:00\",\"dateModified\":\"2024-12-21T21:00:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/first.global\\\/press-releases\\\/intel-partners-with-first-global-for-a-2023-student-maker-cohort-focused-on-neural-code-innovation\\\/\"},\"wordCount\":1309,\"publisher\":{\"@id\":\"https:\\\/\\\/first.global\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/first.global\\\/press-releases\\\/intel-partners-with-first-global-for-a-2023-student-maker-cohort-focused-on-neural-code-innovation\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/first.global\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/Intel_LOGO-2.png?fit=600%2C400&ssl=1\",\"articleSection\":[\"Press Releases\",\"Uncategorized\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/first.global\\\/press-releases\\\/intel-partners-with-first-global-for-a-2023-student-maker-cohort-focused-on-neural-code-innovation\\\/\",\"url\":\"https:\\\/\\\/first.global\\\/press-releases\\\/intel-partners-with-first-global-for-a-2023-student-maker-cohort-focused-on-neural-code-innovation\\\/\",\"name\":\"Intel partners with FIRST Global for a 2023 Student Maker Cohort focused on neural code innovation - FIRST Global\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/first.global\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/first.global\\\/press-releases\\\/intel-partners-with-first-global-for-a-2023-student-maker-cohort-focused-on-neural-code-innovation\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/first.global\\\/press-releases\\\/intel-partners-with-first-global-for-a-2023-student-maker-cohort-focused-on-neural-code-innovation\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/first.global\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/Intel_LOGO-2.png?fit=600%2C400&ssl=1\",\"datePublished\":\"2022-12-01T20:52:07+00:00\",\"dateModified\":\"2024-12-21T21:00:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/first.global\\\/press-releases\\\/intel-partners-with-first-global-for-a-2023-student-maker-cohort-focused-on-neural-code-innovation\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/first.global\\\/press-releases\\\/intel-partners-with-first-global-for-a-2023-student-maker-cohort-focused-on-neural-code-innovation\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/first.global\\\/press-releases\\\/intel-partners-with-first-global-for-a-2023-student-maker-cohort-focused-on-neural-code-innovation\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/first.global\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/Intel_LOGO-2.png?fit=600%2C400&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/first.global\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/Intel_LOGO-2.png?fit=600%2C400&ssl=1\",\"width\":600,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/first.global\\\/press-releases\\\/intel-partners-with-first-global-for-a-2023-student-maker-cohort-focused-on-neural-code-innovation\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/first.global\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Intel partners with FIRST Global for a 2023 Student Maker Cohort focused on neural code innovation\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/first.global\\\/#website\",\"url\":\"https:\\\/\\\/first.global\\\/\",\"name\":\"FIRST Global\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/first.global\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/first.global\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/first.global\\\/#organization\",\"name\":\"FIRST Global\",\"url\":\"https:\\\/\\\/first.global\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/first.global\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/first.global\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/FG_Logo-black.png?fit=4656%2C1267&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/first.global\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/FG_Logo-black.png?fit=4656%2C1267&ssl=1\",\"width\":4656,\"height\":1267,\"caption\":\"FIRST Global\"},\"image\":{\"@id\":\"https:\\\/\\\/first.global\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/F1RSTglobal\",\"https:\\\/\\\/x.com\\\/F1RSTglobal\",\"http:\\\/\\\/instagram.com\\\/f1rstglobal\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/f1rst-global\",\"http:\\\/\\\/youtube.com\\\/@f1rstglobal\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/first.global\\\/#\\\/schema\\\/person\\\/3b3ac653fa313ed64d0ee0c119cc8f7d\",\"name\":\"FIRST Global\",\"url\":\"https:\\\/\\\/first.global\\\/fr\\\/author\\\/kacey\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Intel s'associe \u00e0 FIRST Global pour une cohorte d'\u00e9tudiants Maker 2023 ax\u00e9e sur l'innovation du code neuronal - FIRST Global","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/first.global\/fr\/press-releases\/intel-partners-with-first-global-for-a-2023-student-maker-cohort-focused-on-neural-code-innovation\/","og_locale":"fr_FR","og_type":"article","og_title":"Intel partners with FIRST Global for a 2023 Student Maker Cohort focused on neural code innovation - FIRST Global","og_description":"&nbsp; For 2023, Intel is sponsoring a Student Maker Cohort intended to create a community for shared learning between industry leaders, technologists, and the next generation of student makers, who will contribute to the application of Artificial Intelligence (AI) for industry innovation. In January 2023,...","og_url":"https:\/\/first.global\/fr\/press-releases\/intel-partners-with-first-global-for-a-2023-student-maker-cohort-focused-on-neural-code-innovation\/","og_site_name":"FIRST Global","article_publisher":"http:\/\/facebook.com\/F1RSTglobal","article_published_time":"2022-12-01T20:52:07+00:00","article_modified_time":"2024-12-21T21:00:06+00:00","og_image":[{"width":600,"height":400,"url":"https:\/\/eadn-wc05-4108819.nxedge.io\/wp-content\/uploads\/2018\/08\/Intel_LOGO-2.png","type":"image\/png"}],"author":"FIRST Global","twitter_card":"summary_large_image","twitter_creator":"@F1RSTglobal","twitter_site":"@F1RSTglobal","twitter_misc":{"\u00c9crit par":"FIRST Global","Dur\u00e9e de lecture estim\u00e9e":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/first.global\/press-releases\/intel-partners-with-first-global-for-a-2023-student-maker-cohort-focused-on-neural-code-innovation\/#article","isPartOf":{"@id":"https:\/\/first.global\/press-releases\/intel-partners-with-first-global-for-a-2023-student-maker-cohort-focused-on-neural-code-innovation\/"},"author":{"name":"FIRST Global","@id":"https:\/\/first.global\/#\/schema\/person\/3b3ac653fa313ed64d0ee0c119cc8f7d"},"headline":"Intel partners with FIRST Global for a 2023 Student Maker Cohort focused on neural code innovation","datePublished":"2022-12-01T20:52:07+00:00","dateModified":"2024-12-21T21:00:06+00:00","mainEntityOfPage":{"@id":"https:\/\/first.global\/press-releases\/intel-partners-with-first-global-for-a-2023-student-maker-cohort-focused-on-neural-code-innovation\/"},"wordCount":1309,"publisher":{"@id":"https:\/\/first.global\/#organization"},"image":{"@id":"https:\/\/first.global\/press-releases\/intel-partners-with-first-global-for-a-2023-student-maker-cohort-focused-on-neural-code-innovation\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/first.global\/wp-content\/uploads\/2018\/08\/Intel_LOGO-2.png?fit=600%2C400&ssl=1","articleSection":["Press Releases","Uncategorized"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/first.global\/press-releases\/intel-partners-with-first-global-for-a-2023-student-maker-cohort-focused-on-neural-code-innovation\/","url":"https:\/\/first.global\/press-releases\/intel-partners-with-first-global-for-a-2023-student-maker-cohort-focused-on-neural-code-innovation\/","name":"Intel s'associe \u00e0 FIRST Global pour une cohorte d'\u00e9tudiants Maker 2023 ax\u00e9e sur l'innovation du code neuronal - FIRST Global","isPartOf":{"@id":"https:\/\/first.global\/#website"},"primaryImageOfPage":{"@id":"https:\/\/first.global\/press-releases\/intel-partners-with-first-global-for-a-2023-student-maker-cohort-focused-on-neural-code-innovation\/#primaryimage"},"image":{"@id":"https:\/\/first.global\/press-releases\/intel-partners-with-first-global-for-a-2023-student-maker-cohort-focused-on-neural-code-innovation\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/first.global\/wp-content\/uploads\/2018\/08\/Intel_LOGO-2.png?fit=600%2C400&ssl=1","datePublished":"2022-12-01T20:52:07+00:00","dateModified":"2024-12-21T21:00:06+00:00","breadcrumb":{"@id":"https:\/\/first.global\/press-releases\/intel-partners-with-first-global-for-a-2023-student-maker-cohort-focused-on-neural-code-innovation\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/first.global\/press-releases\/intel-partners-with-first-global-for-a-2023-student-maker-cohort-focused-on-neural-code-innovation\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/first.global\/press-releases\/intel-partners-with-first-global-for-a-2023-student-maker-cohort-focused-on-neural-code-innovation\/#primaryimage","url":"https:\/\/i0.wp.com\/first.global\/wp-content\/uploads\/2018\/08\/Intel_LOGO-2.png?fit=600%2C400&ssl=1","contentUrl":"https:\/\/i0.wp.com\/first.global\/wp-content\/uploads\/2018\/08\/Intel_LOGO-2.png?fit=600%2C400&ssl=1","width":600,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/first.global\/press-releases\/intel-partners-with-first-global-for-a-2023-student-maker-cohort-focused-on-neural-code-innovation\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/first.global\/"},{"@type":"ListItem","position":2,"name":"Intel partners with FIRST Global for a 2023 Student Maker Cohort focused on neural code innovation"}]},{"@type":"WebSite","@id":"https:\/\/first.global\/#website","url":"https:\/\/first.global\/","name":"FIRST Global","description":"","publisher":{"@id":"https:\/\/first.global\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/first.global\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/first.global\/#organization","name":"FIRST Global","url":"https:\/\/first.global\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/first.global\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/first.global\/wp-content\/uploads\/2017\/10\/FG_Logo-black.png?fit=4656%2C1267&ssl=1","contentUrl":"https:\/\/i0.wp.com\/first.global\/wp-content\/uploads\/2017\/10\/FG_Logo-black.png?fit=4656%2C1267&ssl=1","width":4656,"height":1267,"caption":"FIRST Global"},"image":{"@id":"https:\/\/first.global\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/F1RSTglobal","https:\/\/x.com\/F1RSTglobal","http:\/\/instagram.com\/f1rstglobal","https:\/\/www.linkedin.com\/company\/f1rst-global","http:\/\/youtube.com\/@f1rstglobal"]},{"@type":"Person","@id":"https:\/\/first.global\/#\/schema\/person\/3b3ac653fa313ed64d0ee0c119cc8f7d","name":"FIRST Global","url":"https:\/\/first.global\/fr\/author\/kacey\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/first.global\/wp-content\/uploads\/2018\/08\/Intel_LOGO-2.png?fit=600%2C400&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9kXwL-8WV","jetpack-related-posts":[{"id":21351,"url":"https:\/\/first.global\/fr\/2019-nations\/iraq-2019\/","url_meta":{"origin":34405,"position":0},"title":"\u00c9quipe Irak 2019 \ud83c\uddee\ud83c\uddf6","author":"FIRST Global","date":"juillet 25, 2019","format":false,"excerpt":"","rel":"","context":"Dans &quot;2019 Nations&quot;","block_context":{"text":"2019 Nations","link":"https:\/\/first.global\/fr\/category\/2019-nations\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/first.global\/wp-content\/uploads\/2019\/07\/Team-Iraq-2019.jpg?fit=1067%2C800&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/first.global\/wp-content\/uploads\/2019\/07\/Team-Iraq-2019.jpg?fit=1067%2C800&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/first.global\/wp-content\/uploads\/2019\/07\/Team-Iraq-2019.jpg?fit=1067%2C800&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/first.global\/wp-content\/uploads\/2019\/07\/Team-Iraq-2019.jpg?fit=1067%2C800&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/first.global\/wp-content\/uploads\/2019\/07\/Team-Iraq-2019.jpg?fit=1067%2C800&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":33555,"url":"https:\/\/first.global\/fr\/2023-nations\/guyana-2023\/","url_meta":{"origin":34405,"position":1},"title":"\u00c9quipe Guyane 2023 \ud83c\uddec\ud83c\uddfe","author":"FIRST Global","date":"d\u00e9cembre 2, 2023","format":false,"excerpt":"Clause de non-responsabilit\u00e9 : Le langage, les opinions et les images affich\u00e9s sur cette page de profil d'\u00e9quipe sont ceux de cette \u00e9quipe et ne refl\u00e8tent pas n\u00e9cessairement les points de vue ou les positions de FIRST Global.","rel":"","context":"Dans &quot;2023 Nations&quot;","block_context":{"text":"2023 Nations","link":"https:\/\/first.global\/fr\/category\/2023-nations\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/first.global\/wp-content\/uploads\/2024\/12\/Guyana-2023.jpg?fit=1200%2C532&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/first.global\/wp-content\/uploads\/2024\/12\/Guyana-2023.jpg?fit=1200%2C532&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/first.global\/wp-content\/uploads\/2024\/12\/Guyana-2023.jpg?fit=1200%2C532&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/first.global\/wp-content\/uploads\/2024\/12\/Guyana-2023.jpg?fit=1200%2C532&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/first.global\/wp-content\/uploads\/2024\/12\/Guyana-2023.jpg?fit=1200%2C532&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":33433,"url":"https:\/\/first.global\/fr\/in-the-news\/lam-research-cultivates-future-stem-talent-at-2023-first-global-challenge-in-singapore\/","url_meta":{"origin":34405,"position":2},"title":"Lam Research cultive les futurs talents STEM au 2023 FIRST Global Challenge \u00e0 Singapour","author":"FIRST Global","date":"novembre 9, 2023","format":false,"excerpt":"Le FIRST Global Challenge 2023 s'est achev\u00e9 dans la vibrante ville de Singapour, apr\u00e8s que des lyc\u00e9ens de pr\u00e8s de 200 pays se soient affront\u00e9s dans une bataille intellectuelle et cr\u00e9ative anim\u00e9e dans le domaine de la robotique. Cette septi\u00e8me comp\u00e9tition internationale annuelle de robotique s'est d\u00e9roul\u00e9e pour la premi\u00e8re fois en Asie du Sud-Est, en octobre...","rel":"","context":"Dans &quot;In the News&quot;","block_context":{"text":"In the News","link":"https:\/\/first.global\/fr\/category\/in-the-news\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/first.global\/wp-content\/uploads\/2024\/11\/FirstGlobal_SingaporeD2_jm-11-1.jpg?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/first.global\/wp-content\/uploads\/2024\/11\/FirstGlobal_SingaporeD2_jm-11-1.jpg?fit=1200%2C800&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/first.global\/wp-content\/uploads\/2024\/11\/FirstGlobal_SingaporeD2_jm-11-1.jpg?fit=1200%2C800&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/first.global\/wp-content\/uploads\/2024\/11\/FirstGlobal_SingaporeD2_jm-11-1.jpg?fit=1200%2C800&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/first.global\/wp-content\/uploads\/2024\/11\/FirstGlobal_SingaporeD2_jm-11-1.jpg?fit=1200%2C800&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":33055,"url":"https:\/\/first.global\/fr\/2022-nations\/raq-2022\/","url_meta":{"origin":34405,"position":3},"title":"\u00c9quipe Irak 2022 \ud83c\uddee\ud83c\uddf6","author":"FIRST Global","date":"mai 26, 2022","format":false,"excerpt":"Clause de non-responsabilit\u00e9 : Le langage, les opinions et les images affich\u00e9s sur cette page de profil d'\u00e9quipe sont ceux de cette \u00e9quipe et ne refl\u00e8tent pas n\u00e9cessairement les points de vue ou les positions de FIRST Global.","rel":"","context":"Dans &quot;2022 Nations&quot;","block_context":{"text":"2022 Nations","link":"https:\/\/first.global\/fr\/category\/2022-nations\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/first.global\/wp-content\/uploads\/2024\/11\/Iraq-2022.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/first.global\/wp-content\/uploads\/2024\/11\/Iraq-2022.jpg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/first.global\/wp-content\/uploads\/2024\/11\/Iraq-2022.jpg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/first.global\/wp-content\/uploads\/2024\/11\/Iraq-2022.jpg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/first.global\/wp-content\/uploads\/2024\/11\/Iraq-2022.jpg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":34293,"url":"https:\/\/first.global\/fr\/press-releases\/first-global-announces-lam-research-as-title-sponsor-for-the-2024-first-global-challenge\/","url_meta":{"origin":34405,"position":4},"title":"FIRST Global annonce que Lam Research est le commanditaire principal du FIRST Global Challenge 2024","author":"FIRST Global","date":"septembre 1, 2024","format":false,"excerpt":"Manchester, NH - FIRST Global, l'organisation \u00e0 but non lucratif qui se consacre \u00e0 inspirer les jeunes du monde entier \u00e0 travers le sport de la robotique, est fi\u00e8re d'annoncer que Lam Research est le commanditaire en titre du FIRST Global Challenger 2024. Sous le th\u00e8me \"Nourrir l'avenir\", l'\u00e9v\u00e9nement de cette ann\u00e9e se tiendra \u00e0 Ath\u00e8nes, en Gr\u00e8ce,...","rel":"","context":"Dans &quot;Press Releases&quot;","block_context":{"text":"Press Releases","link":"https:\/\/first.global\/fr\/category\/press-releases\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/first.global\/wp-content\/uploads\/2024\/12\/Lam_Research_logo.jpg?fit=1200%2C527&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/first.global\/wp-content\/uploads\/2024\/12\/Lam_Research_logo.jpg?fit=1200%2C527&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/first.global\/wp-content\/uploads\/2024\/12\/Lam_Research_logo.jpg?fit=1200%2C527&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/first.global\/wp-content\/uploads\/2024\/12\/Lam_Research_logo.jpg?fit=1200%2C527&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/first.global\/wp-content\/uploads\/2024\/12\/Lam_Research_logo.jpg?fit=1200%2C527&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/first.global\/fr\/wp-json\/wp\/v2\/posts\/34405","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/first.global\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/first.global\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/first.global\/fr\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/first.global\/fr\/wp-json\/wp\/v2\/comments?post=34405"}],"version-history":[{"count":1,"href":"https:\/\/first.global\/fr\/wp-json\/wp\/v2\/posts\/34405\/revisions"}],"predecessor-version":[{"id":34406,"href":"https:\/\/first.global\/fr\/wp-json\/wp\/v2\/posts\/34405\/revisions\/34406"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/first.global\/fr\/wp-json\/wp\/v2\/media\/19788"}],"wp:attachment":[{"href":"https:\/\/first.global\/fr\/wp-json\/wp\/v2\/media?parent=34405"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/first.global\/fr\/wp-json\/wp\/v2\/categories?post=34405"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/first.global\/fr\/wp-json\/wp\/v2\/tags?post=34405"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}